{"id":9705,"date":"2024-10-01T19:46:21","date_gmt":"2024-10-02T02:46:21","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=9705"},"modified":"2024-10-01T19:46:24","modified_gmt":"2024-10-02T02:46:24","slug":"hallan-a-modelo-flotando-tras-una-misteriosa-fiesta-en-un-yate","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2024\/10\/01\/hallan-a-modelo-flotando-tras-una-misteriosa-fiesta-en-un-yate\/","title":{"rendered":"Hallan a modelo flotando tras una misteriosa fiesta en un yate."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Adriana Vieira, modelo de OnlyFans de 31 a\u00f1os de edad aparece en Miami \u00bfQu\u00e9 ocurri\u00f3 la noche anterior?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ESTADOS UNIDOS a 01 de octubre del 2024.- Adriana Vieira, una modelo de OnlyFans de origen brasile\u00f1o, fue encontrada muerta flotando en el puerto de Miami el pasado 22 de septiembre. La madre de un ni\u00f1o de seis a\u00f1os fue vista por \u00faltima vez la noche anterior, mientras nadaba despu\u00e9s de asistir a una exclusiva fiesta en un yate, organizada por un rapero cuyo nombre no ha sido revelado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 sabemos del caso?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adriana Vieira, de 31 a\u00f1os, era originaria de S\u00e3o Paulo, Brasil, y hab\u00eda llegado a Florida hace dos a\u00f1os junto a su esposo, Roberto Tesario. Sin embargo, poco despu\u00e9s, Tesario regres\u00f3 a Brasil, dejando a Adriana en Estados Unidos a cargo de su hijo peque\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La \u00faltima vez que fue vista con vida fue durante una fiesta en un yate de lujo, donde se report\u00f3 que estuvo nadando en el puerto la noche del 21 de septiembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su cuerpo fue encontrado flotando en las aguas al d\u00eda siguiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Investigaci\u00f3n en curso<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La polic\u00eda de Miami a\u00fan no ha emitido declaraciones oficiales sobre las circunstancias de la muerte de la modelo, y el cuerpo de Adriana est\u00e1 siendo sometido a una autopsia para determinar la causa exacta de su fallecimiento. Hasta el momento, no se han dado a conocer detalles sobre c\u00f3mo lleg\u00f3 a estar en el agua o las posibles causas de su muerte. Adem\u00e1s, el rapero que organiz\u00f3 la fiesta no ha sido identificado ni relacionado con el suceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00daltima publicaci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un inquietante detalle surgi\u00f3 al conocerse que Adriana comparti\u00f3 una \u00faltima fotograf\u00eda el d\u00eda antes de su muerte. En la imagen se ve a dos mujeres en bikini a bordo de un yate, con una botella de champ\u00e1n en primer plano. Esta ser\u00eda la \u00faltima instant\u00e1nea antes de que su vida terminara en circunstancias a\u00fan no aclaradas.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"276\" class=\"wp-image-9707\" style=\"width: 500px;\" src=\"https:\/\/elreporterodelacomunidad.com\/storage\/2024\/10\/Captura-1.jpg\" alt=\"\" srcset=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2024\/10\/Captura-1.jpg 493w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2024\/10\/Captura-1-300x166.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desesperaci\u00f3n de la familia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antonia de Lourdes Vieira, madre de la fallecida, ha pedido p\u00fablicamente que la muerte de su hija sea investigada a fondo. En declaraciones a medios brasile\u00f1os, Antonia expres\u00f3 su temor de que Adriana sea enterrada en una fosa com\u00fan si no puede traer el cuerpo de vuelta a Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, el hijo de seis a\u00f1os de la modelo est\u00e1 bajo el cuidado de una ni\u00f1era, a la espera de que la familia viaje a Estados Unidos para identificar el cuerpo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQuiero que la muerte de mi hija sea investigada y necesito ayuda para traer su cuerpo de regreso\u201d, declar\u00f3 Antonia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vida p\u00fablica y glamorosa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adriana Vieira era conocida en las redes sociales como \u201cLadyRichForever\u201d y compart\u00eda contenido para adultos en OnlyFans, donde ofrec\u00eda a sus suscriptores contenido exclusivo. Tambi\u00e9n trabajaba como modelo y bailarina, y particip\u00f3 en la Semana de la Moda de Miami el a\u00f1o pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su cuenta de Instagram, la modelo mostraba un estilo de vida lleno de lujos, con fotos en Nueva York, Las Vegas y a bordo de yates de lujo. Su perfil reflejaba una vida glamurosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adriana Vieira, modelo de OnlyFans de 31 a\u00f1os de edad aparece en Miami \u00bfQu\u00e9 ocurri\u00f3 la noche anterior? ESTADOS UNIDOS a 01 de octubre del 2024.- Adriana Vieira, una modelo de OnlyFans de origen brasile\u00f1o, fue encontrada muerta flotando en el puerto de Miami el pasado 22 de septiembre. La madre de un ni\u00f1o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-9705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/9705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=9705"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/9705\/revisions"}],"predecessor-version":[{"id":9708,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/9705\/revisions\/9708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/9706"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=9705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=9705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=9705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}