{"id":8779,"date":"2024-09-12T08:42:37","date_gmt":"2024-09-12T15:42:37","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=8779"},"modified":"2024-09-12T08:42:39","modified_gmt":"2024-09-12T15:42:39","slug":"bon-jovi-se-convierte-en-heroe-salva-a-mujer-que-pretendia-saltar-de-un-puente","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2024\/09\/12\/bon-jovi-se-convierte-en-heroe-salva-a-mujer-que-pretendia-saltar-de-un-puente\/","title":{"rendered":"Bon Jovi se convierte en h\u00e9roe; salva a mujer que pretend\u00eda saltar de un puente."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El cantante se encontraba grabando su nuevo video musical, cuando not\u00f3 a la chica en problemas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos a 11 de septiembre del 2024.- Bon Jovi pas\u00f3 de ser una de las m\u00e1s grandes leyendas del rock internacional a un aut\u00e9ntico h\u00e9roe; y es que salv\u00f3 la vida de una mujer que pretend\u00eda tirarse de un puente peatonal en Nashville, Tennessee.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con informaci\u00f3n publicada por TMZ, los hechos ocurrieron este pasado martes, cuando el int\u00e9rprete de &#8220;It&#8217;s my life&#8221; se encontraba en el puente John Seigenthaler para grabar el videoclip de su nuevo sencillo &#8220;People&#8217;s House&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alrededor de las 18:00 horas y mientras hac\u00edan algunas tomas en el lugar, Jovi se percat\u00f3 de que una mujer colgaba del barandal, por lo que paus\u00f3 el rodaje y corri\u00f3 a ofrecerle ayuda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un video que fue publicado en el canal de YouTube del Departamento de Polic\u00eda de Nashville, se puede ver el momento exacto en el que el cantante se acerca a la chica para platicar con ella y tratar de convencerla de que no terminara con su vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque no se sabe con exactitud lo que el artista le dijo a la mujer, bastaron solo un par de segundas para que \u00e9sta cambiara de opini\u00f3n y, con ayuda de Bon Jovi y otro transe\u00fante que se encontraba en el lugar, la ayudaran a ponerse a salvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El sitio tambi\u00e9n explic\u00f3 que Bon Jovi estuvo acompa\u00f1ando a la mujer hasta que llegaron oficiales de polic\u00eda y miembros del escuadr\u00f3n de bomberos, quienes no s\u00f3lo lo felicitaron por su pronta intervenci\u00f3n; sino que instaron a los presentes a actuar ante una situaci\u00f3n similar: &#8220;es necesario que todos ayudemos a mantenernos seguros unos a otros&#8221;, dijo John Drake, jefe del departamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantante se encontraba grabando su nuevo video musical, cuando not\u00f3 a la chica en problemas. Estados Unidos a 11 de septiembre del 2024.- Bon Jovi pas\u00f3 de ser una de las m\u00e1s grandes leyendas del rock internacional a un aut\u00e9ntico h\u00e9roe; y es que salv\u00f3 la vida de una mujer que pretend\u00eda tirarse de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-8779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/8779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=8779"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/8779\/revisions"}],"predecessor-version":[{"id":8781,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/8779\/revisions\/8781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/8780"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=8779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=8779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=8779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}