{"id":6097,"date":"2024-07-08T19:43:18","date_gmt":"2024-07-09T02:43:18","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=6097"},"modified":"2024-07-08T19:43:20","modified_gmt":"2024-07-09T02:43:20","slug":"la-actriz-margot-robbie-y-su-esposo-tom-ackerley-esperan-su-primer-hijo-afirma-la-revista-people","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2024\/07\/08\/la-actriz-margot-robbie-y-su-esposo-tom-ackerley-esperan-su-primer-hijo-afirma-la-revista-people\/","title":{"rendered":"La actriz Margot Robbie y su esposo Tom Ackerley esperan su primer hijo, afirma la revista People."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EUA a 08 de Julio del 2024.- EFE.- La actriz y productora australiana Margot Robbie est\u00e1 embarazada y, junto a su marido Tom Ackerley, esperan su primer hijo, seg\u00fan inform\u00f3 este domingo el medio de celebridades People.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los representantes de Margot Robbie y Tom Ackerley a\u00fan no han confirmado la noticia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cM\u00faltiples fuentes confirman a People que la estrella de Barbie, de 34 a\u00f1os, y su marido, Tom Ackerley, est\u00e1n esperando su primer beb\u00e9\u201d, comunic\u00f3 igualmente el medio enfocado en temas de la industria del entretenimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La relaci\u00f3n personal entre la protagonista de \u201cBarbie\u201d con Ackerley, actor y productor brit\u00e1nico que como Robbie tambi\u00e9n tiene 34 a\u00f1os, comenz\u00f3 en el a\u00f1o 2013 tras conocerse en el rodaje del drama \u201cSuite francesa\u201d (en espa\u00f1ol), donde ella hac\u00eda el papel de Celine y \u00e9l se desempa\u00f1aba como ayudante de direcci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, durante los primeros meses fueron s\u00f3lo amigos. Despu\u00e9s de trabajar juntos en la productora LuckyChap, donde tambi\u00e9n est\u00e1n Sophia Kerr y Josey McNamara, surgir\u00eda el noviazgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pareja, que siempre ha mantenido su romance en privado, no anunci\u00f3 su compromiso antes de casarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2016, finalmente contrajeron matrimonio en una ceremonia privada en Byron Bay (Australia) y recientemente Ackerle dijo que sobrellevan su faceta profesional y personal de una manera \u201cperfecta\u201d, pasando \u201clas 24 horas del d\u00eda juntos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, hoy mismo han aparecido nuevas fotos en internet que muestran a Robbie con la barriga al descubierto y ligeramente abultada durante unas vacaciones en el Lago de Como (Italia), lo que tambi\u00e9n ha hecho pensar a muchos que espera su primer hijo con su marido Tom Ackerley.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUA a 08 de Julio del 2024.- EFE.- La actriz y productora australiana Margot Robbie est\u00e1 embarazada y, junto a su marido Tom Ackerley, esperan su primer hijo, seg\u00fan inform\u00f3 este domingo el medio de celebridades People. Los representantes de Margot Robbie y Tom Ackerley a\u00fan no han confirmado la noticia. \u201cM\u00faltiples fuentes confirman a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,39],"tags":[],"class_list":["post-6097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","category-politica"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/6097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=6097"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/6097\/revisions"}],"predecessor-version":[{"id":6099,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/6097\/revisions\/6099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/6098"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=6097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=6097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=6097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}