{"id":5264,"date":"2024-06-13T21:41:43","date_gmt":"2024-06-14T04:41:43","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=5264"},"modified":"2024-06-13T21:41:45","modified_gmt":"2024-06-14T04:41:45","slug":"falsa-alerta-de-bomba-interrumpe-concierto-de-christian-nodal-en-ecuador","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2024\/06\/13\/falsa-alerta-de-bomba-interrumpe-concierto-de-christian-nodal-en-ecuador\/","title":{"rendered":"Falsa alerta de bomba interrumpe concierto de Christian Nodal en Ecuador."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Polic\u00eda Nacional de Ecuador se moviliz\u00f3 al recinto de Ecuador e interrumpi\u00f3 el concierto de Christian Nodal mientras investigaba la supuesta amenaza de bomba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El p\u00e1nico se desat\u00f3 entre el p\u00fablico que asist\u00eda a un concierto gratuito de Christian Nodal en la provincia de El Oro, Ecuador. Las autoridades de seguridad arribaron al lugar para investigar un posible atentado con bomba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El concierto se realizaba como parte de la celebraci\u00f3n por los 200 a\u00f1os de cantonizaci\u00f3n de Machala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a distintas versiones, los asistentes comenzaron a gritar mientras la cantante Katty Barrero realizaba su presentaci\u00f3n previa a Christian Nodal. De inmediato, la Polic\u00eda Nacional, presente en el recinto, tom\u00f3 control de la situaci\u00f3n y pidi\u00f3 suspender el concierto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presentaci\u00f3n de Nodal se ten\u00eda prevista para las 21:00 horas. Adem\u00e1s, se esperaba la aparici\u00f3n de la cantante Angela Aguilar, su actual pareja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Minutos despu\u00e9s, la Polic\u00eda Nacional de Ecuador dijo que presumiblemente se trat\u00f3 de una \u201cfalsa alarma\u201d, pero insisti\u00f3 en que los asistentes al concierto mantuvieran la calma mientras se realizaba la investigaci\u00f3n al completo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfReanudaron el concierto?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de la amenaza de bomba, las personas permanecieron cerca del recinto. Videos que circulan en redes sociales muestran como la polic\u00eda se desplazaba por el lugar revisando las instalaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Videos miestran como la polic\u00eda recupera una mochila abandona en el lugar. Hasta ahora no han confirmado que contuviera un dispositivo explosivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La interrupci\u00f3n del concierto demor\u00f3 alrededor de una hora, tras la cual la polic\u00eda descart\u00f3 se tratara de una verdadera amenaza de bomba, por lo cual reanudaron el concierto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de las 21:30 horas, Christian Nodal subi\u00f3 al escenario para realizar su presentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jornada violenta<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La amenaza de bomba sucedi\u00f3 en medio de una jornada violenta en Ecuador. Tan solo unas horas antes se dio a conocer el asesinato de una persona en la zona donde se realizaba el concierto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la polic\u00eda confirm\u00f3 que a lo largo de la tarde se reportaron varios robos y atentados violentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por si fuera poco, agencias de noticias dieron a conocer que las morgues de Guayaquil est\u00e1n rebasadas por los numerosos casos de asesinato que han tenido que atender en las \u00faltimas 72 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda Nacional de Ecuador se moviliz\u00f3 al recinto de Ecuador e interrumpi\u00f3 el concierto de Christian Nodal mientras investigaba la supuesta amenaza de bomba. El p\u00e1nico se desat\u00f3 entre el p\u00fablico que asist\u00eda a un concierto gratuito de Christian Nodal en la provincia de El Oro, Ecuador. Las autoridades de seguridad arribaron al lugar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-5264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/5264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=5264"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/5264\/revisions"}],"predecessor-version":[{"id":5266,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/5264\/revisions\/5266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/5265"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=5264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=5264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=5264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}