{"id":31979,"date":"2026-07-14T17:02:51","date_gmt":"2026-07-15T00:02:51","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=31979"},"modified":"2026-07-14T17:02:51","modified_gmt":"2026-07-15T00:02:51","slug":"refuerza-tono-astiazaran-prevencion-en-colonias-con-la-instalacion-del-centro-de-respuesta-inmediata-numero-21","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2026\/07\/14\/refuerza-tono-astiazaran-prevencion-en-colonias-con-la-instalacion-del-centro-de-respuesta-inmediata-numero-21\/","title":{"rendered":"Refuerza To\u00f1o Astiazar\u00e1n prevenci\u00f3n en colonias con la instalaci\u00f3n del Centro de Respuesta Inmediata n\u00famero 21"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Est\u00e1 ubicado en la colonia Villa Verde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 14 de julio, 2026.- Al entregar el Centro de Respuesta Inmediata (CRI) n\u00famero 21 a residentes de la colonia Villa Verde, en el Norponiente de Hermosillo, el presidente municipal Antonio Astiazar\u00e1n Guti\u00e9rrez confirm\u00f3 a estas sedes de la Polic\u00eda Preventiva y Tr\u00e1nsito Municipal como una apuesta correcta a favor de la prevenci\u00f3n en el municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la entrega formal de una nueva instalaci\u00f3n de la corporaci\u00f3n, equipada con un veh\u00edculo el\u00e9ctrico para el reforzamiento de la vigilancia preventiva y atenci\u00f3n de reportes en el sector, To\u00f1o Astiazar\u00e1n destac\u00f3 que las distintas estrategias en materia de seguridad implementadas desde que asumi\u00f3 la responsabilidad de gobernar a la capital sonorense en 2021 han confirmado su efectividad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSin duda alguna que la apuesta que estamos haciendo para mejorar los espacios p\u00fablicos, para activar los espacios p\u00fablicos, para tener la presencia de la Polic\u00eda Municipal m\u00e1s r\u00e1pido cuando la requerimos, y evitar con ello los delitos en las viviendas, sin duda es la apuesta correcta, por eso les agradezco infinitamente todo su apoyo, toda la confianza que han tenido en el equipo del Gobierno Municipal\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" class=\"wp-image-31981\" style=\"width: 500px;\" src=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/ee705466-e1c0-4bdf-a12b-8e811d281015.jpg\" alt=\"\" srcset=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/ee705466-e1c0-4bdf-a12b-8e811d281015.jpg 1280w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/ee705466-e1c0-4bdf-a12b-8e811d281015-300x200.jpg 300w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/ee705466-e1c0-4bdf-a12b-8e811d281015-1024x682.jpg 1024w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/ee705466-e1c0-4bdf-a12b-8e811d281015-768x512.jpg 768w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/ee705466-e1c0-4bdf-a12b-8e811d281015-750x500.jpg 750w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/ee705466-e1c0-4bdf-a12b-8e811d281015-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">To\u00f1o Astiazar\u00e1n entreg\u00f3 a la se\u00f1ora Mar\u00eda Antonieta Valle, representante de las y los vecinos de la colonia Villa Verde y sus alrededores, la llave del nuevo Centro de Respuesta Inmediata, y al agente Jos\u00e9 Alejandro Andrade Ruiz las llaves del veh\u00edculo el\u00e9ctrico asignado a dicha sede, misma que en adelante estar\u00e1 bajo su responsabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sostuvo que los CRI; los 155 corredores Camina Segura; la mejora en las condiciones de trabajo de los agentes; la inversi\u00f3n en patrullas el\u00e9ctricas y en la rehabilitaci\u00f3n de parques y canchas deportivas, as\u00ed como su activaci\u00f3n por medio de promotores deportivos apoyados por el Ayuntamiento, son estrategias cuyo prop\u00f3sito en com\u00fan es mejorar la seguridad para todas y todos los residentes de Hermosillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo acompa\u00f1aron en esta entrega, Alonso Dur\u00f3n Monta\u00f1o, Comisario General de la Polic\u00eda Preventiva y Tr\u00e1nsito Municipal; Daniel Garc\u00eda Escalante, director de Participaci\u00f3n Ciudadana; Sergio Pavlovich Escalante, director de Servicios P\u00fablicos Municipales; Ram\u00f3n Corral Aguirre, Oficial Mayor; Oscar Gast\u00e9lum Donnadieu, director de la Agencia Municipal de Desarrollo Econ\u00f3mico (AMDE) y el regidor Orlando Cuevas, as\u00ed como mandos medios y superiores de la corporaci\u00f3n policiaca municipal.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" class=\"wp-image-31982\" style=\"width: 500px;\" src=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/8d371e8d-dd10-43a4-8faa-645cdc6dba08.jpg\" alt=\"\" srcset=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/8d371e8d-dd10-43a4-8faa-645cdc6dba08.jpg 1280w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/8d371e8d-dd10-43a4-8faa-645cdc6dba08-300x200.jpg 300w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/8d371e8d-dd10-43a4-8faa-645cdc6dba08-1024x682.jpg 1024w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/8d371e8d-dd10-43a4-8faa-645cdc6dba08-768x512.jpg 768w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/8d371e8d-dd10-43a4-8faa-645cdc6dba08-750x500.jpg 750w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2026\/07\/8d371e8d-dd10-43a4-8faa-645cdc6dba08-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 ubicado en la colonia Villa Verde. Hermosillo, Sonora; 14 de julio, 2026.- Al entregar el Centro de Respuesta Inmediata (CRI) n\u00famero 21 a residentes de la colonia Villa Verde, en el Norponiente de Hermosillo, el presidente municipal Antonio Astiazar\u00e1n Guti\u00e9rrez confirm\u00f3 a estas sedes de la Polic\u00eda Preventiva y Tr\u00e1nsito Municipal como una apuesta [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31980,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,26],"tags":[],"class_list":["post-31979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-principal"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/31979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=31979"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/31979\/revisions"}],"predecessor-version":[{"id":31983,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/31979\/revisions\/31983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/31980"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=31979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=31979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=31979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}