{"id":25121,"date":"2025-11-27T13:13:22","date_gmt":"2025-11-27T20:13:22","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=25121"},"modified":"2025-11-27T13:13:31","modified_gmt":"2025-11-27T20:13:31","slug":"incauta-policia-estatal-mas-de-200-envoltorios-de-narcotico-en-acciones-contra-el-narcomenudeo-en-hermosillo","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/11\/27\/incauta-policia-estatal-mas-de-200-envoltorios-de-narcotico-en-acciones-contra-el-narcomenudeo-en-hermosillo\/","title":{"rendered":"Incauta Polic\u00eda Estatal m\u00e1s de 200 envoltorios de narc\u00f3tico en acciones contra el narcomenudeo en Hermosillo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 27 de noviembre de 2025.- Grupos t\u00e1cticos de la Polic\u00eda Estatal de Seguridad P\u00fablica (PESP) intensificaron los recorridos de prevenci\u00f3n y vigilancia en zonas focalizadas asegurando durante estas acciones a dos hombres que transportaban envoltorios con narc\u00f3tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En trabajo operativo realizado el mi\u00e9rcoles 26 de noviembre en la colonia Villas del Sur, se logr\u00f3 la detenci\u00f3n de Gilberto \u201cN\u201d, de 28 a\u00f1os de edad al incautarle 103 envoltorios con narc\u00f3tico, 36 de estos con hierba verde y 67 con sustancia granulada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, en el sector Las Villas, la Polic\u00eda Estatal detuvo a Carlos \u201cN\u201d, de 33 a\u00f1os por posesi\u00f3n de 118 envoltorios con sustancia prohibida, 38 de ellos con materia granulada y el resto hierba verde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los polic\u00edas estatales llevaron a cabo el arresto de las personas, quienes fueron informadas sobre los derechos de los detenidos y quedaron a disposici\u00f3n del Ministerio P\u00fablico para las averiguaciones correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la capital sonorense contin\u00faa la presencia operativa de la Polic\u00eda Estatal, que coadyuva con autoridades de seguridad de los tres niveles de gobierno en acciones de prevenci\u00f3n y combate al delito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nota: Se informa que las personas detenidas se presumen inocentes y ser\u00e1n tratadas como tales en todas las etapas del procedimiento, mientras no se declare su responsabilidad mediante sentencia emitida por el \u00f3rgano jurisdiccional correspondiente, conforme al art\u00edculo 13 del C\u00f3digo Nacional de Procedimientos Penales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora a 27 de noviembre de 2025.- Grupos t\u00e1cticos de la Polic\u00eda Estatal de Seguridad P\u00fablica (PESP) intensificaron los recorridos de prevenci\u00f3n y vigilancia en zonas focalizadas asegurando durante estas acciones a dos hombres que transportaban envoltorios con narc\u00f3tico. En trabajo operativo realizado el mi\u00e9rcoles 26 de noviembre en la colonia Villas del Sur, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-25121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/25121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=25121"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/25121\/revisions"}],"predecessor-version":[{"id":25123,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/25121\/revisions\/25123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/25122"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=25121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=25121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=25121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}