{"id":21882,"date":"2025-08-17T20:16:40","date_gmt":"2025-08-18T03:16:40","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=21882"},"modified":"2025-08-17T20:16:48","modified_gmt":"2025-08-18T03:16:48","slug":"operativos-entre-amic-semar-y-defensa-captura-a-personas-y-aseguran-armas-droga-y-rescatan-a-menores-en-puerto-penasco-y-nogales","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/08\/17\/operativos-entre-amic-semar-y-defensa-captura-a-personas-y-aseguran-armas-droga-y-rescatan-a-menores-en-puerto-penasco-y-nogales\/","title":{"rendered":"Operativos entre AMIC, SEMAR y DEFENSA captura a personas y aseguran armas, droga y rescatan a menores en Puerto Pe\u00f1asco y Nogales."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las personas detenidas y los objetos asegurados fueron puestos a disposici\u00f3n de la Fiscal\u00eda General de la Rep\u00fablica (FGR).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora, 17 de agosto de 2025.- Como parte de las labores estrat\u00e9gicas de investigaci\u00f3n y seguridad, la Agencia Ministerial de Investigaci\u00f3n Criminal (AMIC) ejecut\u00f3 diversas acciones coordinadas con fuerzas de SEMAR y DEFENSA, que derivaron en la captura de personas, aseguramiento de armas, droga y equipo de comunicaci\u00f3n, en hechos ocurridos en los municipios de Puerto Pe\u00f1asco y Nogales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una primera intervenci\u00f3n, derivada de recorridos de reconocimiento y disuasi\u00f3n apoyados con un dron, personal de la AMIC y la Secretar\u00eda de Marina Armada de M\u00e9xico (SEMAR) localiz\u00f3 un campamento improvisado en un cerro, a 20 kil\u00f3metros del casco urbano de Puerto Pe\u00f1asco, en inmediaciones de Laguna Shores e Islas del Mar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el sitio se detuvo a Eduardo \u201cN\u201d, de 29 a\u00f1os, originario de Sinaloa, quien se encontraba en posesi\u00f3n de un fusil de asalto AR-15 con 59 cartuchos calibre .223, una pistola calibre 9 mil\u00edmetros con 17 cartuchos, un par de binoculares, un radio transmisor y 7 gramos de marihuana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un segundo hecho, en Nogales, elementos de la AMIC y de la Secretar\u00eda de la Defensa Nacional (DEFENSA) dieron cumplimiento a una orden de cateo en un domicilio ubicado en la calle Yorem, colonia Colinas del Yaqui.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el sitio fueron asegurados Hiram \u201cN\u201d, de 40 a\u00f1os; \u00d3scar \u201cN\u201d, de 49; Ezequiel \u201cN\u201d, de 31; Merary Ayde \u201cN\u201d, de 28; y Sara \u201cN\u201d, de 67 a\u00f1os. En la acci\u00f3n tambi\u00e9n fueron rescatados tres menores de edad, una ni\u00f1a de 11 a\u00f1os y dos ni\u00f1os de 13 y 5 a\u00f1os, quienes quedaron bajo resguardo del Sistema DIF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como indicios, se aseguraron una pistola calibre .22, dos escopetas, calibres 12 y 20, un rifle de madera sin serie ni leyenda, 16 envoltorios con droga \u201ccristal\u201d, 36 envoltorios con coca\u00edna y un cartucho marcado \u201cLC23\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las personas detenidas y los objetos asegurados fueron puestos a disposici\u00f3n del Agente del Ministerio P\u00fablico Federal adscrito a la Delegaci\u00f3n Sonora de la Fiscal\u00eda General de la Rep\u00fablica (FGR) para las investigaciones correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda General de Justicia del Estado de Sonora (FGJES) refrenda su compromiso con la legalidad, el debido proceso y la coordinaci\u00f3n interinstitucional, fortaleciendo la seguridad p\u00fablica y la atenci\u00f3n a las denuncias ciudadanas en todo el territorio estatal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las personas detenidas y los objetos asegurados fueron puestos a disposici\u00f3n de la Fiscal\u00eda General de la Rep\u00fablica (FGR). Hermosillo, Sonora, 17 de agosto de 2025.- Como parte de las labores estrat\u00e9gicas de investigaci\u00f3n y seguridad, la Agencia Ministerial de Investigaci\u00f3n Criminal (AMIC) ejecut\u00f3 diversas acciones coordinadas con fuerzas de SEMAR y DEFENSA, que derivaron [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-21882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=21882"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21882\/revisions"}],"predecessor-version":[{"id":21884,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21882\/revisions\/21884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/21883"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=21882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=21882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=21882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}