{"id":21850,"date":"2025-08-16T21:36:52","date_gmt":"2025-08-17T04:36:52","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=21850"},"modified":"2025-08-16T21:36:56","modified_gmt":"2025-08-17T04:36:56","slug":"hallan-siete-laboratorios-clandestinos-y-un-plantio-en-sinaloa","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/08\/16\/hallan-siete-laboratorios-clandestinos-y-un-plantio-en-sinaloa\/","title":{"rendered":"Hallan siete laboratorios clandestinos y un plant\u00edo en Sinaloa."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Estos fueron encontrados en las comunidades del Potrero de los Ibarra de Abajo, Los Sabinitos, Los Vasitos, El Vino, El Habal y en las inmediaciones de la presa Vinoramas, en la capital sinaloense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Culiac\u00e1n, Sinaloa a 16 de agosto de 2025 (Reforma).- Autoridades federales y estatales aseguraron y destruyeron siete laboratorios clandestinos y un plant\u00edo de mariguana en los municipios de Culiac\u00e1n y Cosal\u00e1, en Sinaloa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La Secretar\u00eda de Seguridad P\u00fablica del estado inform\u00f3 este s\u00e1bado que en el marco de la &#8216;Operaci\u00f3n B\u00fasqueda, Localizaci\u00f3n y Destrucci\u00f3n de Laboratorios Clandestinos&#8217; localiz\u00f3 seis \u00e1reas de concentraci\u00f3n de materiales qu\u00edmicos utilizados para la elaboraci\u00f3n de drogas sint\u00e9ticas en las comunidades de Potrero de los Ibarra de Abajo, Los Sabinitos, Los Vasitos, El Vino, El Habal y en las inmediaciones de la presa Vinoramas, en la capital sinaloense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En el poblado El Ranchito, en Cosal\u00e1, localiz\u00f3 otro laboratorio en el que precis\u00f3 el aseguramiento de 31 bidones con mil 610 litros de acetona, nueve tambos con mil 890 litros de metanol, nueve bidones con aproximadamente 480 litros de alcohol et\u00edlico, as\u00ed como una olla con aproximadamente 10 litros de precursores qu\u00edmicos y otros tres bidones que tambi\u00e9n conten\u00eda 100 litros de precursores qu\u00edmicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Adem\u00e1s de seis bidones con 300 litros de tolueno y seis m\u00e1s con 300 litros de \u00e1cido clorh\u00eddrico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Entre otras cosas, en ese laboratorio la dependencia tambi\u00e9n report\u00f3 el hallazgo de tres costales con 150 kilogramos de sosa c\u00e1ustica en escamas, tres bidones con 75 litros de sustancias desconocidas y un sistema de almacenamiento de agua improvisado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0En el poblado Camanaca, perteneciente al municipio de Culiac\u00e1n, la SSP local indic\u00f3 que militares localizaron y destruyeron un plant\u00edo de mariguana con una superficie de 100 metros cuadrados, con una densidad de seis plantas por metro cuadrado y una altura promedio de 1.5 metros.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"272\" class=\"wp-image-21852\" style=\"width: 500px;\" src=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/08\/ppp.jpg\" alt=\"\" srcset=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/08\/ppp.jpg 696w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/08\/ppp-300x163.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estos fueron encontrados en las comunidades del Potrero de los Ibarra de Abajo, Los Sabinitos, Los Vasitos, El Vino, El Habal y en las inmediaciones de la presa Vinoramas, en la capital sinaloense. Culiac\u00e1n, Sinaloa a 16 de agosto de 2025 (Reforma).- Autoridades federales y estatales aseguraron y destruyeron siete laboratorios clandestinos y un plant\u00edo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-21850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=21850"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21850\/revisions"}],"predecessor-version":[{"id":21853,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21850\/revisions\/21853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/21851"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=21850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=21850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=21850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}