{"id":21497,"date":"2025-08-06T15:39:59","date_gmt":"2025-08-06T22:39:59","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=21497"},"modified":"2025-08-06T15:40:05","modified_gmt":"2025-08-06T22:40:05","slug":"sonora-garantiza-proteccion-y-atencion-a-victimas-de-violencia-con-primera-estancia-temporal-dif","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/08\/06\/sonora-garantiza-proteccion-y-atencion-a-victimas-de-violencia-con-primera-estancia-temporal-dif\/","title":{"rendered":"Sonora garantiza protecci\u00f3n y atenci\u00f3n a v\u00edctimas de violencia con primera estancia temporal: DIF."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Esta estancia temporal para mujeres y sus hijas e hijos v\u00edctimas de violencia, promovida por el gobernador Alfonso Durazo, ofrecer\u00e1 asesor\u00eda jur\u00eddica, m\u00e9dica, psicol\u00f3gica, acompa\u00f1amiento social y apoyo para el emprendimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta honoraria del DIF Sonora, Roc\u00edo Ch\u00e1vez Murillo, dio a conocer las acciones que contempla este proyecto, cuyo objetivo es proteger a las familias sonorenses y construir comunidades m\u00e1s emp\u00e1ticas y seguras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 6 de agosto de 2025.- Por primera vez en Sonora, el gobernador Alfonso Durazo Monta\u00f1o consolida una estrategia integral que busca transformar la atenci\u00f3n institucional con un enfoque de derechos humanos, perspectiva de g\u00e9nero y restituci\u00f3n plena de derechos. Esto se materializa a trav\u00e9s del Programa de Atenci\u00f3n a Mujeres, Ni\u00f1as, Ni\u00f1os y Adolescentes V\u00edctimas de Violencia Extrema, as\u00ed como del proyecto de la Estancia Temporal Estatal para Mujeres, sus Hijas e Hijos en situaci\u00f3n de violencia extrema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta honoraria del Sistema para el Desarrollo Integral de la Familia (DIF) Sonora, Mar\u00eda del Roc\u00edo Ch\u00e1vez Murillo, present\u00f3 este programa durante un encuentro con representantes de diversas instituciones, organizaciones y empresarios. Detall\u00f3 que las acciones est\u00e1n enfocadas en construir entornos m\u00e1s seguros para las familias sonorenses, como la creaci\u00f3n de la primera estancia temporal para mujeres y sus hijas e hijos, ubicada en Hermosillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cInvito y agradezco a todas las mujeres a trabajar en conjunto, porque as\u00ed es como m\u00e1s se puede potenciar la ayuda para todas las personas v\u00edctimas de violencia. Ya visit\u00e9 el centro, va a quedar con mucha dignidad; ojal\u00e1 ninguna mujer necesitara ocupar ese espacio, pero sabemos que existe\u201d, enfatiz\u00f3 Ch\u00e1vez Murillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la comisionada ejecutiva estatal de Atenci\u00f3n a V\u00edctimas de Sonora (CEEAV), Lyzeth Salcedo Salinas, se\u00f1al\u00f3 que el programa brindar\u00e1 atenci\u00f3n jur\u00eddica, m\u00e9dica y psicol\u00f3gica especializada, as\u00ed como acompa\u00f1amiento social y estrategias de econom\u00eda personal y comunitaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHoy no venimos solamente a presentar un modelo; venimos a honrar una deuda hist\u00f3rica con las mujeres que han vivido lo impensable: violencias que arrancan hogares, rompen cuerpos, vulneran infancias y fracturan proyectos de vida. Pero tambi\u00e9n venimos a decir que s\u00ed es posible sanar, proteger y reconstruir si lo hacemos juntas y juntos\u201d, asegur\u00f3 Salcedo Salinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La estancia temporal representa una inversi\u00f3n superior a los 21 millones de pesos y actualmente presenta un avance f\u00edsico del 25 por ciento. El proyecto contempla \u00e1reas comunes, de servicio, de atenci\u00f3n, y rec\u00e1maras para atender a 21 familias de manera simult\u00e1nea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas acciones, el gobernador Alfonso Durazo Monta\u00f1o refuerza su compromiso con las mujeres de Sonora, consciente de la necesidad de su cuidado. Este espacio seguro brindar\u00e1 atenci\u00f3n emocional y f\u00edsica por parte de personal capacitado, as\u00ed como el apoyo necesario para que las mujeres y sus familias puedan salir adelante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta estancia temporal para mujeres y sus hijas e hijos v\u00edctimas de violencia, promovida por el gobernador Alfonso Durazo, ofrecer\u00e1 asesor\u00eda jur\u00eddica, m\u00e9dica, psicol\u00f3gica, acompa\u00f1amiento social y apoyo para el emprendimiento. La presidenta honoraria del DIF Sonora, Roc\u00edo Ch\u00e1vez Murillo, dio a conocer las acciones que contempla este proyecto, cuyo objetivo es proteger a las [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-21497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=21497"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21497\/revisions"}],"predecessor-version":[{"id":21499,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21497\/revisions\/21499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/21498"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=21497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=21497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=21497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}