{"id":21037,"date":"2025-07-21T13:04:28","date_gmt":"2025-07-21T20:04:28","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=21037"},"modified":"2025-07-21T13:04:31","modified_gmt":"2025-07-21T20:04:31","slug":"ampliara-sec-estrategia-de-aprendizajes-fundamentales-a-todas-las-primarias-en-sonora","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/07\/21\/ampliara-sec-estrategia-de-aprendizajes-fundamentales-a-todas-las-primarias-en-sonora\/","title":{"rendered":"Ampliar\u00e1 SEC estrategia de aprendizajes fundamentales a todas las primarias en Sonora."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 21 de julio de 2025.- Para beneficiar a m\u00e1s de 120 mil estudiantes de primero a tercer grado de primaria, con materiales, docentes y figuras de acompa\u00f1amiento altamente capacitados, el Gobierno de Sonora ampliar\u00e1 la Estrategia Integral de Aprendizajes Fundamentales (EIAF) al 100 por ciento de las escuelas durante el ciclo escolar 2025-2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de la Secretar\u00eda de Educaci\u00f3n y Cultura (SEC), se inici\u00f3 la implementaci\u00f3n de dicha estrategia en 2023, la cual est\u00e1 avalada por la Unesco y busca que un mayor n\u00famero de ni\u00f1as y ni\u00f1os mejoren sus conocimientos y habilidades en lenguaje para lograr su alfabetizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El titular de la SEC, Froyl\u00e1n G\u00e1mez Gamboa, destac\u00f3 la colaboraci\u00f3n con Fundaci\u00f3n Coppel, Instituto Natura, Unesco, Faro Social y Educativo, V\u00eda Educaci\u00f3n y Fundaci\u00f3n Zorro Rojo, como parte de una pol\u00edtica p\u00fablica de fortalecimiento a la profesionalizaci\u00f3n de la estructura educativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la implementaci\u00f3n de la estrategia participar\u00e1n docentes, jefes de sector y figuras educativas, quienes recibir\u00e1n material did\u00e1ctico, formaci\u00f3n continua y acompa\u00f1amiento, con el prop\u00f3sito de fortalecer una metodolog\u00eda enfocada en la adquisici\u00f3n y consolidaci\u00f3n de la alfabetizaci\u00f3n inicial del alumnado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante una reuni\u00f3n de an\u00e1lisis sobre la evoluci\u00f3n de la EIAF, la subsecretaria de Pol\u00edticas Educativas para la Transformaci\u00f3n, Guadalupe Gonz\u00e1lez Liz\u00e1rraga, y el director general de Educaci\u00f3n Primaria, Pablo Salom\u00f3n Montiel, abordaron los logros, fortalezas y desaf\u00edos para el pr\u00f3ximo ciclo escolar, as\u00ed como las condiciones necesarias para cumplir con el objetivo de cubrir la totalidad de las primarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado de la jornada, se establecieron 26 acuerdos estrat\u00e9gicos y operativos, relacionados con los seis componentes de la EIAF, a los que se dar\u00e1 seguimiento en las sesiones de Mesa T\u00e9cnica y a nivel operativo cada semana, a fin de que, al inicio del ciclo escolar 2025-2026, se cuente con todas las condiciones necesarias para lograr los objetivos de la EIAF en todas las primarias del estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 21 de julio de 2025.- Para beneficiar a m\u00e1s de 120 mil estudiantes de primero a tercer grado de primaria, con materiales, docentes y figuras de acompa\u00f1amiento altamente capacitados, el Gobierno de Sonora ampliar\u00e1 la Estrategia Integral de Aprendizajes Fundamentales (EIAF) al 100 por ciento de las escuelas durante el ciclo escolar 2025-2026. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-21037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=21037"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21037\/revisions"}],"predecessor-version":[{"id":21039,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/21037\/revisions\/21039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/21038"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=21037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=21037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=21037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}