{"id":20852,"date":"2025-07-15T21:08:13","date_gmt":"2025-07-16T04:08:13","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=20852"},"modified":"2025-07-15T21:08:18","modified_gmt":"2025-07-16T04:08:18","slug":"pepe-aguilar-le-abrio-un-concierto-a-soda-stereo-y-le-negaron-acceso-a-su-camerino","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/07\/15\/pepe-aguilar-le-abrio-un-concierto-a-soda-stereo-y-le-negaron-acceso-a-su-camerino\/","title":{"rendered":"Pepe Aguilar le abri\u00f3 un concierto a Soda St\u00e9reo y le negaron acceso a su camerino."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El cantante Pepe Aguilar record\u00f3 cuando le abri\u00f3 un concierto a Soda St\u00e9reo y no lo dejaron entrar a su camerino para saludarlos, tocaba con su grupo de rock Equs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico a 15 de julio de 2025.- Pepe Aguilar es un personaje muy conocido dentro de la m\u00fasica popular de nuestro pa\u00eds con casi 35 a\u00f1os de carrera art\u00edstica, principalmente en el mariachi y la balada ranchera, siguiendo la tradici\u00f3n familiar de sus padres que cantaban este mismo g\u00e9nero y aparte eran grandes actores: Antonio Aguilar y Flor Silvestre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero es bien sabido tambi\u00e9n del gusto que tiene el cantante nacido en San Antonio, Texas, por el rock, por lo que tiene un pasado enfocado en ese g\u00e9nero durante su adolescencia, quien se aferr\u00f3 a esa idea durante un par de a\u00f1os, en contra de los deseos de su padre y fue en esa etapa cuando conoci\u00f3 a Gustavo Cerati, l\u00edder de la banda argentina Soda St\u00e9reo en 1987.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los argentinos ven\u00eda de gira a nuestro pa\u00eds y ya contaban con 4 discos de estudio y su primer \u00e1lbum en vivo, que para ese entonces ya ten\u00eda los \u00e9xitos \u201cPersiana Americana\u201d, Signos\u201d, \u201cCuando pase el temblor\u201d, \u201cUn misil en mi placard\u201d, y \u201cNada personal\u201d entre muchos otros, por lo que llegaba ya como una banda estrella y consagrada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando vino Soda Stereo, la disquera no sab\u00eda donde meterlos porque no hab\u00eda espacios para tocar, eran contados y de pronto Soda Stereo por eso tuvo que hacer hoteles donde se presentaba antes Enrique Guzm\u00e1n y toda esta onda, en el Fiesta Americana y cosas as\u00ed, de hecho en una de esas fechas Pepe Aguilar les abri\u00f3, pero con Equs\u201d, menciona Chava Rock en la participaci\u00f3n que tuvo en un podcast de Jessie Cervantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cantante dio sus primeros pasos en la m\u00fasica desde ni\u00f1o, pero fue en su adolescencia cuando conform\u00f3 esta banda de rock a la que bautizaron como Equs, en donde el precursor de la dinast\u00eda Aguilar compon\u00eda sus propias canciones y fueron sus primeros pasos como m\u00fasico profesional a la edad de 19, cuando corr\u00eda el a\u00f1o de 1985.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa primera vez que lo conoc\u00ed le abrimos en lo que era el Hotel de M\u00e9xico que ahora es el World Trade Center, un lugar donde hacen eventos, pero en ese entonces era como el estacionamiento y ah\u00ed toc\u00f3 Soda St\u00e9reo, toc\u00f3 Kenny y Los El\u00e9ctricos y toc\u00f3 Equs, fue nuestro primer concierto, le abrimos a Soda St\u00e9reo y ah\u00ed fue la primera vez que lo conoc\u00ed\u201d, record\u00f3 el propio cantante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esa etapa primigenia dentro del mundo de la m\u00fasica en realidad dur\u00f3 muy poco con todo y que la banda alcanz\u00f3 a publicar un disco y solo se mantuvieron activos de 1985 a 1987, a\u00f1o en el que pas\u00f3 esa primera anecdota con Gustavo Cerati, y algunos a\u00f1os despu\u00e9s tom\u00f3 el camino con el que lo conocemos hasta la actualidad dentro de la m\u00fasica regional mexicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo con muy buen resultado porque yo pens\u00e9 que a ese nivel, a abrirle a Soda St\u00e9reo, pues ya \u00e9ramos todos iguales, artistas \u00bfno?, pues no, no es as\u00ed el rollo, cuando quise ir a saludarlos como igual, pues no me dejaron entrar al camerino, oye pero yo voy a tocar, s\u00ed, no hay problema, la segunda vez fue con este amigo y no se quiso subir a mi camioneta\u201d, record\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pepe Aguilar todav\u00eda no ten\u00eda nombre dentro de la escena musical y era natural que un grupo ya consagrado y aparte de origen argentino, le negara siquiera la posibilidad de saludarlos directamente, adem\u00e1s Gustavo Cerati, junto con Charly Alberti y Zeta Bosio eran m\u00fasicos muy comprometidos con su m\u00fasica, que trabajaban a detalle y tal vez por eso prefer\u00edan no ser molestados en su camerino, previo a una presentaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantante Pepe Aguilar record\u00f3 cuando le abri\u00f3 un concierto a Soda St\u00e9reo y no lo dejaron entrar a su camerino para saludarlos, tocaba con su grupo de rock Equs. Ciudad de M\u00e9xico a 15 de julio de 2025.- Pepe Aguilar es un personaje muy conocido dentro de la m\u00fasica popular de nuestro pa\u00eds con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-20852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/20852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=20852"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/20852\/revisions"}],"predecessor-version":[{"id":20854,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/20852\/revisions\/20854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/20853"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=20852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=20852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=20852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}