{"id":19595,"date":"2025-06-12T14:21:33","date_gmt":"2025-06-12T21:21:33","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=19595"},"modified":"2025-06-12T14:21:42","modified_gmt":"2025-06-12T21:21:42","slug":"reconoce-gobierno-de-sonora-a-participantes-de-la-olimpiada-del-conocimiento-infantil-2025-sec","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/06\/12\/reconoce-gobierno-de-sonora-a-participantes-de-la-olimpiada-del-conocimiento-infantil-2025-sec\/","title":{"rendered":"Reconoce Gobierno de Sonora a participantes de la Olimpiada del Conocimiento Infantil 2025: SEC."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 12 de junio de 2025.- Despu\u00e9s de superar las etapas escolar y regional, un total de 156 estudiantes de sexto grado de primaria, provenientes de distintos municipios del estado, participaron en la etapa final de la Olimpiada del Conocimiento Infantil (OCI) 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno de Sonora, a trav\u00e9s de la Secretar\u00eda de Educaci\u00f3n y Cultura (SEC), reconoci\u00f3 el esfuerzo del alumnado, as\u00ed como el acompa\u00f1amiento de sus familias y docentes, por impulsarlos a destacar en estos encuentros acad\u00e9micos que fortalecen la transformaci\u00f3n educativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En representaci\u00f3n del titular de la SEC, Froyl\u00e1n G\u00e1mez Gamboa, el director general de Educaci\u00f3n Primaria, Pablo Salom\u00f3n Montiel, destac\u00f3 que este tipo de convocatorias tienen como prop\u00f3sito impulsar la transformaci\u00f3n educativa y respaldar las aptitudes sobresalientes del alumnado que se prepara en cada escuela de Sonora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El alumnado fue evaluado en los cuatro campos formativos del plan de estudios de la Nueva Escuela Mexicana (NEM): \u00c9tica, Naturaleza y Sociedades; De lo humano y lo comunitario; Lenguajes; y Saberes y Pensamientos Cient\u00edficos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La aplicaci\u00f3n del examen se realiz\u00f3 en las instalaciones del Colegio de Bachilleres del Estado de Sonora (Cobach), plantel \u201cErnesto L\u00f3pez Riesgo\u201d, y fue supervisada por personal educativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta etapa estatal, se seleccionar\u00e1 a 19 ni\u00f1as y ni\u00f1os de primaria urbana, rural, ind\u00edgena, Conafe y escuelas particulares, quienes recibir\u00e1n una beca econ\u00f3mica mensual durante los tres a\u00f1os de estudio en educaci\u00f3n secundaria, otorgada por la Fundaci\u00f3n BBVA Bancomer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora a 12 de junio de 2025.- Despu\u00e9s de superar las etapas escolar y regional, un total de 156 estudiantes de sexto grado de primaria, provenientes de distintos municipios del estado, participaron en la etapa final de la Olimpiada del Conocimiento Infantil (OCI) 2025. El Gobierno de Sonora, a trav\u00e9s de la Secretar\u00eda de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-19595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/19595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=19595"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/19595\/revisions"}],"predecessor-version":[{"id":19597,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/19595\/revisions\/19597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/19596"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=19595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=19595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=19595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}