{"id":19591,"date":"2025-06-12T14:18:45","date_gmt":"2025-06-12T21:18:45","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=19591"},"modified":"2025-06-12T14:18:48","modified_gmt":"2025-06-12T21:18:48","slug":"promueve-ayuntamiento-de-hermosillo-oportunidades-de-capacitacion-a-adolescentes-infractores","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/06\/12\/promueve-ayuntamiento-de-hermosillo-oportunidades-de-capacitacion-a-adolescentes-infractores\/","title":{"rendered":"Promueve Ayuntamiento de Hermosillo oportunidades de capacitaci\u00f3n a adolescentes infractores."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">-UMPAM Hermosillo y el Centro de Capacitaci\u00f3n para el Trabajo Industrial (CECATI) se coordinaron para ofrecerles un taller t\u00e9cnico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 12 de junio de 2025.- Adolescentes que cometieron faltas administrativas en Hermosillo se graduaron del primer Taller T\u00e9cnico en Electricidad Dom\u00e9stica que la Unidad Municipal de Prevenci\u00f3n y Aplicaci\u00f3n de Medidas (UMPAM) Hermosillo les ofreci\u00f3 como parte de las acciones a favor de su reinserci\u00f3n exitosa a la comunidad, en alianza con CECATI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotros le apostamos a la prevenci\u00f3n y a la reinserci\u00f3n, no le apostamos a la criminalizaci\u00f3n de nuestros j\u00f3venes, es por eso que enarbolamos este tipo de proyectos\u201d, estableci\u00f3 David Rojas, director operativo de Secretar\u00eda del Ayuntamiento, quien encabez\u00f3 la ceremonia con la representaci\u00f3n del Presidente Municipal Antonio Astiazar\u00e1n Guti\u00e9rrez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la entrega de sus respectivos reconocimientos a 10 graduados y 2 graduadas lo acompa\u00f1aron Alonso Dur\u00f3n Monta\u00f1o, titular de la jefatura de la Polic\u00eda Preventiva y Tr\u00e1nsito Municipal; Martha Gabriela Yunu\u00e9 Flores Contreras, titular de UMPAM, el regidor Aurelio Orlando Cuevas Ramos y Ernesto Isaac R\u00edos director de CECATI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCelebramos no solo la culminaci\u00f3n de un curso de electricidad, sino tambi\u00e9n un importante paso hacia un futuro mejor para cada uno de ustedes, quiero felicitar a estos 12 j\u00f3venes que han demostrado compromiso, dedicaci\u00f3n y ganas de aprender\u201d, expres\u00f3 Dur\u00f3n Monta\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director de Centro de Capacitaci\u00f3n para el Trabajo Industrial (CECATI) Ernesto Isaac R\u00edos felicit\u00f3 a las y los graduados por haber cumplido la meta que este taller t\u00e9cnico les plant\u00f3 y los alent\u00f3 a abordar nuevos retos y oportunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les hizo saber, y a sus familias presentes, que CECATI tiene las puertas abiertas para ofrecerles habilidades y destrezas con los que podr\u00e1n incorporarse al sector productivo y generar ingresos econ\u00f3micos.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"327\" class=\"wp-image-19593\" style=\"width: 500px;\" src=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/06\/26da2d7d-c7f9-41df-a665-a9574a39e3ed.jpg\" alt=\"\" srcset=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/06\/26da2d7d-c7f9-41df-a665-a9574a39e3ed.jpg 1600w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/06\/26da2d7d-c7f9-41df-a665-a9574a39e3ed-300x196.jpg 300w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/06\/26da2d7d-c7f9-41df-a665-a9574a39e3ed-1024x669.jpg 1024w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/06\/26da2d7d-c7f9-41df-a665-a9574a39e3ed-768x502.jpg 768w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/06\/26da2d7d-c7f9-41df-a665-a9574a39e3ed-1536x1003.jpg 1536w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/06\/26da2d7d-c7f9-41df-a665-a9574a39e3ed-750x490.jpg 750w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/06\/26da2d7d-c7f9-41df-a665-a9574a39e3ed-1140x745.jpg 1140w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>-UMPAM Hermosillo y el Centro de Capacitaci\u00f3n para el Trabajo Industrial (CECATI) se coordinaron para ofrecerles un taller t\u00e9cnico Hermosillo, Sonora a 12 de junio de 2025.- Adolescentes que cometieron faltas administrativas en Hermosillo se graduaron del primer Taller T\u00e9cnico en Electricidad Dom\u00e9stica que la Unidad Municipal de Prevenci\u00f3n y Aplicaci\u00f3n de Medidas (UMPAM) Hermosillo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-19591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/19591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=19591"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/19591\/revisions"}],"predecessor-version":[{"id":19594,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/19591\/revisions\/19594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/19592"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=19591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=19591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=19591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}