{"id":19045,"date":"2025-05-29T21:10:50","date_gmt":"2025-05-30T04:10:50","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=19045"},"modified":"2025-05-29T21:10:52","modified_gmt":"2025-05-30T04:10:52","slug":"alfonso-durazo-suma-esfuerzos-con-gobierno-de-mexico-para-fortalecer-tranquilidad-social-con-programa-si-al-desarme-si-a-la-paz","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/05\/29\/alfonso-durazo-suma-esfuerzos-con-gobierno-de-mexico-para-fortalecer-tranquilidad-social-con-programa-si-al-desarme-si-a-la-paz\/","title":{"rendered":"Alfonso Durazo suma esfuerzos con Gobierno de M\u00e9xico para fortalecer tranquilidad social con programa \u201cS\u00ed al Desarme, S\u00ed a la Paz\u201d."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El gobernador Alfonso Durazo puso en marcha en Sonora el programa nacional de la presidenta Claudia Sheinbaum \u201cS\u00ed al Desarme, S\u00ed a la Paz\u201d, con el objetivo de inhibir la violencia mediante el canje voluntario de armas y promover una cultura de paz; jornadas en las que participa personal del Ej\u00e9rcito Mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En seguimiento al programa nacional de fortalecimiento a la seguridad, el mandatario estatal se\u00f1al\u00f3 que en Sonora se han decomisado m\u00e1s de 1,447 armas largas de enero a octubre de 2024. En estas jornadas de canje tambi\u00e9n se fomenta la no violencia desde la infancia con el intercambio de juguetes b\u00e9licos por did\u00e1cticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 29 de mayo de 2025.- Con el firme compromiso de construir una sociedad m\u00e1s segura y pac\u00edfica, en coordinaci\u00f3n con el Gobierno de M\u00e9xico que encabeza la presidenta Claudia Sheinbaum Pardo, el gobernador Alfonso Durazo Monta\u00f1o puso en marcha en Hermosillo el programa \u201cS\u00ed al Desarme, S\u00ed a la Paz\u201d, una iniciativa nacional que busca promover el canje voluntario de armas y una cultura de no violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el evento, el mandatario estatal subray\u00f3 la importancia de esta estrategia integral, basada en la colaboraci\u00f3n entre instituciones de los tres niveles de gobierno y sociedad civil. Uno de los factores clave para lograr la pacificaci\u00f3n, dijo, es el desarme, la reducci\u00f3n y eliminaci\u00f3n de armas que puedan ser empleadas para generar violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta campa\u00f1a \u2018S\u00ed al desarme, S\u00ed a la Paz\u2019 es una v\u00eda para contribuir a una sociedad sin violencia. Este programa inici\u00f3 en la Ciudad de M\u00e9xico, impulsado por la doctora Claudia Sheinbaum, y dio all\u00e1 extraordinarios resultados que buscamos alcanzar aqu\u00ed en Sonora. Sin coacci\u00f3n, sin coerci\u00f3n, el gobierno, las instituciones, los padres de familia, estudiantes y organizaciones sociales pueden ayudarnos a acercarnos a la poblaci\u00f3n y construir juntos la paz por la v\u00eda del desarme\u201d, expres\u00f3 Durazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobernador detall\u00f3 que la jornada de canje de armas se llevar\u00e1 a cabo del 29 al 31 de mayo, de 8:00 a 14:00 horas, en la Plaza de la Bandera del Centro de Gobierno, en Hermosillo. A quienes acudan, se les garantiza la protecci\u00f3n de su identidad y de los datos recabados, sin consecuencias jur\u00eddicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte esencial del programa, ni\u00f1as y ni\u00f1os participaron intercambiando juguetes b\u00e9licos por juguetes did\u00e1cticos, fomentando desde la infancia valores de convivencia, aprendizaje y rechazo a la violencia. Esta acci\u00f3n simb\u00f3lica representa un paso significativo en la formaci\u00f3n de nuevas generaciones comprometidas con la armon\u00eda social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al finalizar, el gobernador Alfonso Durazo reafirm\u00f3 su compromiso con esta causa y convoc\u00f3 a las y los sonorenses a sumarse a la iniciativa:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa paz se construye con acciones firmes y con la participaci\u00f3n de todas y todos. Juntas y juntos, lograremos un Sonora con paz y tranquilidad\u201d, concluy\u00f3.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"349\" class=\"wp-image-19047\" style=\"width: 500px;\" src=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/05\/IMG-20250529-WA0054.jpg\" alt=\"\" srcset=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/05\/IMG-20250529-WA0054.jpg 1200w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/05\/IMG-20250529-WA0054-300x209.jpg 300w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/05\/IMG-20250529-WA0054-1024x714.jpg 1024w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/05\/IMG-20250529-WA0054-768x536.jpg 768w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/05\/IMG-20250529-WA0054-750x523.jpg 750w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/05\/IMG-20250529-WA0054-1140x795.jpg 1140w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Alfonso Durazo puso en marcha en Sonora el programa nacional de la presidenta Claudia Sheinbaum \u201cS\u00ed al Desarme, S\u00ed a la Paz\u201d, con el objetivo de inhibir la violencia mediante el canje voluntario de armas y promover una cultura de paz; jornadas en las que participa personal del Ej\u00e9rcito Mexicano. En seguimiento al [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-19045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/19045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=19045"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/19045\/revisions"}],"predecessor-version":[{"id":19048,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/19045\/revisions\/19048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/19046"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=19045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=19045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=19045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}