{"id":17395,"date":"2025-04-11T14:29:15","date_gmt":"2025-04-11T21:29:15","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=17395"},"modified":"2025-04-11T14:29:28","modified_gmt":"2025-04-11T21:29:28","slug":"avanza-sec-en-la-organizacion-del-ciclo-escolar-2025-2026-froylan-gamez","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/04\/11\/avanza-sec-en-la-organizacion-del-ciclo-escolar-2025-2026-froylan-gamez\/","title":{"rendered":"Avanza SEC en la organizaci\u00f3n del ciclo escolar 2025-2026: Froyl\u00e1n G\u00e1mez."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 11 de abril de 2025.- Con el objetivo de identificar nuevas necesidades de personal docente y de apoyo en las escuelas p\u00fablicas de educaci\u00f3n b\u00e1sica, as\u00ed como prever y asegurar los recursos necesarios para ofrecer una educaci\u00f3n de excelencia, la SEC llev\u00f3 a cabo reuniones regionales de trabajo con la estructura educativa, como parte de la organizaci\u00f3n del ciclo escolar 2025-2026, inform\u00f3 Froyl\u00e1n G\u00e1mez Gamboa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El titular de la Secretar\u00eda de Educaci\u00f3n y Cultura (SEC) indic\u00f3 que, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica, se convoc\u00f3 a cerca de 400 jefes de sector y supervisores escolares, as\u00ed como a autoridades educativas y sindicales, para el an\u00e1lisis y seguimiento de la Programaci\u00f3n Detallada de Docentes y Personal de Apoyo (Prodet).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los encuentros, que se realizaron en varias sedes del estado, forman parte del esfuerzo para garantizar la suficiencia de aulas y docentes que permitan atender con calidad al alumnado de preescolar, primaria y secundaria desde el primer d\u00eda de clases, en l\u00ednea con el compromiso del gobernador Alfonso Durazo de transformar la sociedad sonorense desde las aulas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">G\u00e1mez Gamboa a\u00f1adi\u00f3 que, de acuerdo con los procedimientos establecidos, anualmente la Direcci\u00f3n General de Planeaci\u00f3n de la SEC entrega oficialmente dicha programaci\u00f3n de las escuelas federalizadas a la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) y de las estatales a la Secretar\u00eda de Hacienda del Gobierno de Sonora, para la asignaci\u00f3n de recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, detall\u00f3 que se realiza un an\u00e1lisis de las necesidades registradas a trav\u00e9s de la Prodet en m\u00e1s de dos mil escuelas p\u00fablicas de nivel b\u00e1sico de la entidad, con la participaci\u00f3n de personal de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica, la Direcci\u00f3n General de Planeaci\u00f3n, as\u00ed como de representantes de las secciones 28 y 54 del SNTE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora a 11 de abril de 2025.- Con el objetivo de identificar nuevas necesidades de personal docente y de apoyo en las escuelas p\u00fablicas de educaci\u00f3n b\u00e1sica, as\u00ed como prever y asegurar los recursos necesarios para ofrecer una educaci\u00f3n de excelencia, la SEC llev\u00f3 a cabo reuniones regionales de trabajo con la estructura educativa, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-17395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/17395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=17395"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/17395\/revisions"}],"predecessor-version":[{"id":17397,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/17395\/revisions\/17397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/17396"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=17395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=17395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=17395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}