{"id":17239,"date":"2025-04-08T18:42:32","date_gmt":"2025-04-09T01:42:32","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=17239"},"modified":"2025-04-08T18:42:34","modified_gmt":"2025-04-09T01:42:34","slug":"instala-ayuntamiento-de-hermosillo-senalamientos-preventivos-por-cruce-de-tortugas-en-el-vado-del-rio","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/04\/08\/instala-ayuntamiento-de-hermosillo-senalamientos-preventivos-por-cruce-de-tortugas-en-el-vado-del-rio\/","title":{"rendered":"Instala Ayuntamiento de Hermosillo se\u00f1alamientos preventivos por cruce de tortugas en el Vado del R\u00edo."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">-Se solicita qua los conductores disminuyan la velocidad para proteger a los reptiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 08 de abril de 2025.- Personal del Ayuntamiento de Hermosillo coloc\u00f3 cuatro se\u00f1alamientos para reforzar el aviso a los conductores que transitan por Paseo del R\u00edo Sonora que es necesario la disminuci\u00f3n de velocidad por el cruce de tortugas que se registra durante esta temporada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">David Palafox Celaya, director del Instituto Municipal de Protecci\u00f3n y Bienestar Animal (IMPBA), coment\u00f3 que el presidente municipal Antonio Astiazar\u00e1n Guti\u00e9rrez instruy\u00f3 a personal a cargo a la instalaci\u00f3n de se\u00f1al\u00e9tica vial nueva en la que fuera muy clara la informaci\u00f3n para los automovilistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se colocaron cuatro letreros en el R\u00edo Sonora, entre Quintero Arce y Quiroga; se contaban con dos ahora son seis, tres de cada lado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDe tal manera de que conozcan sobre el tr\u00e1nsito de tortugas y que haya una reducci\u00f3n importante en la velocidad para que se prevengan accidentes y se proteja a esta especie de animales que por naturaleza transitan para buscar agua y alimento\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Palafox Celaya manifest\u00f3 que existe coordinaci\u00f3n entre varias dependencias del Gobierno Municipal con el fin de informar a la ciudadan\u00eda sobre estas acciones en pro de la protecci\u00f3n animal.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"433\" class=\"wp-image-17241\" style=\"width: 500px;\" src=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/04\/933dd707-74cc-4977-8da2-c1ab88a622e6.jpg\" alt=\"\" srcset=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/04\/933dd707-74cc-4977-8da2-c1ab88a622e6.jpg 1600w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/04\/933dd707-74cc-4977-8da2-c1ab88a622e6-300x260.jpg 300w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/04\/933dd707-74cc-4977-8da2-c1ab88a622e6-1024x887.jpg 1024w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/04\/933dd707-74cc-4977-8da2-c1ab88a622e6-768x665.jpg 768w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/04\/933dd707-74cc-4977-8da2-c1ab88a622e6-1536x1331.jpg 1536w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/04\/933dd707-74cc-4977-8da2-c1ab88a622e6-750x650.jpg 750w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/04\/933dd707-74cc-4977-8da2-c1ab88a622e6-1140x988.jpg 1140w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>-Se solicita qua los conductores disminuyan la velocidad para proteger a los reptiles. Hermosillo, Sonora a 08 de abril de 2025.- Personal del Ayuntamiento de Hermosillo coloc\u00f3 cuatro se\u00f1alamientos para reforzar el aviso a los conductores que transitan por Paseo del R\u00edo Sonora que es necesario la disminuci\u00f3n de velocidad por el cruce de tortugas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-17239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/17239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=17239"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/17239\/revisions"}],"predecessor-version":[{"id":17242,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/17239\/revisions\/17242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/17240"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=17239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=17239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=17239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}