{"id":1715,"date":"2024-03-22T00:00:00","date_gmt":"2024-03-22T07:00:00","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/index.php\/2024\/03\/22\/que-director-del-gobierno-de-sonora-gana-50-mil-pesos-al-mes-trabajando-13-horas-a-la-semana\/"},"modified":"2024-03-22T00:00:00","modified_gmt":"2024-03-22T07:00:00","slug":"que-director-del-gobierno-de-sonora-gana-50-mil-pesos-al-mes-trabajando-13-horas-a-la-semana","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2024\/03\/22\/que-director-del-gobierno-de-sonora-gana-50-mil-pesos-al-mes-trabajando-13-horas-a-la-semana\/","title":{"rendered":"<b>\u00bfQu\u00e9 director del gobierno de Sonora gana 50 mil pesos al mes, trabajando 13 horas a la semana?<\/b>"},"content":{"rendered":"<p class=\"MsoNormal\">Para la envidia de todos esos directores del Gobierno de Sonora, que est\u00e1n d\u00eda y noche al pendiente de sus obligaciones e indicaciones de sus jefes y que dejan a sus familias por cumplir con su trabajo, les puedo decir que, en la Codeson, tienen la oportunidad de estar solo 13 horas a las semanas y seguir ganando poco m\u00e1s de 49 mil pesos, con menos esfuerzo y presiones.<\/p>\n<p class=\"MsoNormal\">Seg\u00fan informaci\u00f3n en la p\u00e1gina <a href=\"https:\/\/www.plataformadetransparencia.org.mx\/\">https:\/\/www.plataformadetransparencia.org.mx\/<\/a> y folio 260488223000070, donde se solicita informaci\u00f3n respecto a horario de trabajo en Codeson, comprobante de sueldo y compatibilidad de horarios en la Universidad Estatal de Sonora (UES) del maestro e investigador de tiempo completo Dr. Manuel Francisco de la Cruz Ortega, Director del Deporte de la Comisi\u00f3n del Deporte del Estado de Sonora, se encontr\u00f3 que:<\/p>\n<p class=\"MsoNormal\">Mediante un memor\u00e1ndum dirigido a la Ing. Zulma Lorenia Noriega Miranda, titular de la Unidad de Transparencia y Acceso a la Informaci\u00f3n, por parte de la Directora de Recursos Humanos de Codeson, Lic. Edith Adria Gonz\u00e1lez Teyechea, respondi\u00f3 lo siguiente:<\/p>\n<p class=\"MsoNormal\">\u201cPor medio de la presente se hace constar que el Dr. Manuel Francisco de la Cruz Ortega quien labora en la Comisi\u00f3n del Deporte del Estado de Sonora desempe\u00f1ando las funciones como Director del Deporte, Adscrito a la Direcci\u00f3n General de esta Entidad, tiene un <b>sueldo mensual de$ 49,110.45 (<\/b> Son: Cuarenta y nueve mil ciento diez pesos 45\/100 MN) antes de impuestos y con un <b>horario laboral de 15:00 a 17:00 horas de Lunes a Viernes y s\u00e1bados de 8:00 a 11:00 horas\u201d.<\/b><\/p>\n<p class=\"MsoNormal\">Asimismo, seg\u00fan la solicitud de compatibilidad, Manuel de la Cruz, con nombramiento del 01 de enero del 2022, tiene un horario de 07:00 a 14:00 horas en la Universidad Estatal de Sonora (UES), como maestro e investigador de tiempo completo, pero ese documento no tiene la firma del rector Armando Moreno Soto.<\/p>\n<p class=\"MsoNormal\">Entonces amigos funcionarios de la 4T, ahora con todos estos movimientos por el proceso electoral, si no fueron elegidos para las boletas de julio y quieren un bajo perfil, hay que buscar una reubicaci\u00f3n en las oficinas ubicadas en la planta baja del estadio de futbol \u201cH\u00e9roe de Nacozari\u201d.<\/p>\n<p class=\"MsoNormal\"><b>Dr. Luis Alberto Durazo Ter\u00e1n, otro funcionario becado en Codeson.<\/b><\/p>\n<p class=\"MsoNormal\">Siguiendo en temas turbios, reportan que Manuel de la Cruz est\u00e1 creando un grupo de apoyo y leal a sus ideas, contratando a compa\u00f1eros de la UES para llevar a cabo su proyecto, apoderarse del mayor numero de espacios en Codeson y con ello, el poder en el deporte.<\/p>\n<p class=\"MsoNormal\">Luis Alberto Durazo Ter\u00e1n, maestro de la UES, es un ex atleta de halterofilia, en su momento, suspendido al dar positivo pruebas de dopaje sus atletas, llega el 01 de octubre del 2023 como subdirector de ciencias aplicadas, nivel 11, con todo el apoyo y la l\u00ednea de seguir las instrucciones de Manuel de la Cruz.<\/p>\n<p class=\"MsoNormal\">Me reportan que es tanto el temor o respeto que le tiene a su jefe, que nada de decide o se mueve si Durazo Ter\u00e1n no lo consulta, es decir, no ha sido una persona resolutiva, perjudicando a entrenadores, atletas y metod\u00f3logos, al no tener facultad para tomar decisiones. Tiene un horario vespertino en Codeson, debido a que da clases por la ma\u00f1ana en UES. <\/p>\n<p class=\"MsoNormal\">Su curr\u00edculum en la p\u00e1gina oficial de Codeson, dice que es doctor en Ciencias de la Cultura F\u00edsica, maestro en metodolog\u00eda del entrenamiento deportivo de alto rendimiento; licenciado en entrenamiento deportivo y miembro del Sistema Nacional de Investigadores.<\/p>\n<p class=\"MsoNormal\">Profesor investigador de tiempo completo en la Universidad Estatal de Sonora y premio estatal del deporte como entrenador.<\/p>\n<p class=\"MsoNormal\"><b>Ana Guevara de nuevo en el Ojo del Hurac\u00e1n en Conade.<\/b><\/p>\n<p class=\"MsoNormal\">Los funcionarios de todos los niveles de gobierno, municipal, estatal y nacional en M\u00e9xico, deben entender que al estar al frente de una instituci\u00f3n p\u00fablica, es importante contar con un equipo de todas sus confianzas, ya que su carrera deportiva, pol\u00edtica o de bur\u00f3crata, est\u00e1n en las manos de sus colaboradores.<\/p>\n<p class=\"MsoNormal\">Porque escribo esto, porque luego de que la Auditor\u00eda Superior de la Federaci\u00f3n (ASF) presentara dos denuncias contra la gesti\u00f3n de Ana Gabriela Guevara en la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte (Conade) por presuntos malos manejos y posibles desv\u00edos que podr\u00edan sumar alrededor de 280 mdp, la Fiscal\u00eda General de la Rep\u00fablica (FGR) encontr\u00f3 diversas irregularidades, entre ellas, facturas falsas de entrenadores \u201cfantasmas\u201d, pagos indebidos y sobreprecio.<\/p>\n<p class=\"MsoNormal\">Adem\u00e1s de la contrataci\u00f3n y pago de servicios mediante intermediarios, los cuales no fueron autorizados o nunca se realizaron, y la realizaci\u00f3n de eventos denominados \u201cespeciales\u201d a muy alto costo.<\/p>\n<p class=\"MsoNormal\">Otras de las irregularidades que destaca la investigaci\u00f3n son los sobornos, alto n\u00famero de pagos a aviadores, y el desfase y pago sobre costo de servicios de la administraci\u00f3n anterior con recursos de la actual.<\/p>\n<p class=\"MsoNormal\">Mientras tanto, el \u00d3rgano Interno de Control (OIC) de la Conade, determin\u00f3 que era culpable por la indebida prestaci\u00f3n de servicios de hospedaje, alimentaci\u00f3n y uso de las instalaciones de Villas Tlalpan a personas que no eran atletas de alto rendimiento y tampoco formaban parte del Sistema Nacional de Cultura F\u00edsica y Deporte (Sinade), ni del Registro Nacional de Cultura F\u00edsica y Deporte (Renade).<\/p>\n<p class=\"MsoNormal\">La investigaci\u00f3n da a conocer que se omitieron pagos a becarios, as\u00ed como el retraso o incumplimiento de pago a personal t\u00e9cnico y deportistas; desproporci\u00f3n y criterios poco transparentes al momento de autorizar giras, viajes o campamentos deportivos a deportistas en procesos clasificatorios, entre otros.<\/p>\n<p class=\"MsoNormal\">El \u00f3rgano fiscalizador detect\u00f3 desde 2020, un presunto desv\u00edo por 205 millones de pesos, de los que la gesti\u00f3n de Guevara s\u00f3lo logr\u00f3 acreditar 55 millones.<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom:0cm;margin-bottom:.0001pt;line-height: 15.75pt;background:white;vertical-align:top\"><b>Por hoy es todo, s\u00edgueme en:<\/b><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom:11.25pt;line-height:15.75pt;background: white;vertical-align:top\">www.elreporterodelacomunidad.com<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom:11.25pt;line-height:15.75pt;background: white;vertical-align:top\">Twitter: @npdeportes1<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom:11.25pt;line-height:15.75pt;background: white;vertical-align:top\">Instagram: npdeportesoficial<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom:11.25pt;line-height:15.75pt;background: white;vertical-align:top\">Tik Tok: npdeportes<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom:11.25pt;line-height:15.75pt;background: white;vertical-align:top\">Youtube: NPDeportes<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom:11.25pt;line-height:15.75pt;background: white;vertical-align:top\">Whatsapp: 6622217136<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para la envidia de todos esos directores del Gobierno de Sonora, que est\u00e1n d\u00eda y noche al pendiente de sus obligaciones e indicaciones de sus jefes y que dejan a sus familias por cumplir con su trabajo, les puedo decir que, en la Codeson, tienen la oportunidad de estar solo 13 horas a las semanas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-1715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nadapersonal"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/1715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=1715"}],"version-history":[{"count":0,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/1715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/1716"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=1715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=1715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=1715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}