{"id":16878,"date":"2025-03-30T14:23:40","date_gmt":"2025-03-30T21:23:40","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=16878"},"modified":"2025-03-30T14:23:43","modified_gmt":"2025-03-30T21:23:43","slug":"conmemoran-legado-y-trascendencia-de-la-escuela-normal-del-estado-creson","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/03\/30\/conmemoran-legado-y-trascendencia-de-la-escuela-normal-del-estado-creson\/","title":{"rendered":"Conmemoran legado y trascendencia de la Escuela Normal del Estado: Creson."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 30 de marzo de 2025.- Con una s\u00f3lida trayectoria en la formaci\u00f3n docente y una visi\u00f3n de innovaci\u00f3n hacia el futuro, la Benem\u00e9rita y Centenaria Escuela Normal del Estado de Sonora \u201cProf. Jes\u00fas Manuel Bustamante Mungarro\u201d (Bycenes) inaugur\u00f3 la agenda de eventos para celebrar su 110 aniversario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En representaci\u00f3n de Froyl\u00e1n G\u00e1mez Gamboa, secretario de Educaci\u00f3n y Cultura, la subsecretaria de Educaci\u00f3n B\u00e1sica, Beatriz Cota Ponce, destac\u00f3 el legado de la Bycenes, la Escuela Normal m\u00e1s antigua del estado, as\u00ed como el compromiso de las y los miles de docentes que se han formado en esta instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl desaf\u00edo es seguir con nuestra vocaci\u00f3n, continuar actualiz\u00e1ndonos, seguir incidiendo en la formaci\u00f3n, pero, sobre todo, tomar conciencia de que nuestra labor est\u00e1 en transformar la vida de nuestras alumnas y alumnos, el entorno y la comunidad educativa\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yazm\u00edn Soto Medina, directora del plantel, resalt\u00f3 que la oferta acad\u00e9mica se ha fortalecido en los \u00faltimos a\u00f1os para responder a los retos del presente y del futuro. Actualmente, se cuenta con tres programas de licenciatura, una maestr\u00eda, una especialidad y, a partir de agosto de este a\u00f1o, comenzar\u00e1 a impartirse un doctorado regional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que, para celebrar los 110 a\u00f1os de la escuela, se ha preparado una agenda de actividades para todo el a\u00f1o, no solo en el \u00e1mbito acad\u00e9mico, sino tambi\u00e9n para rendir homenaje a todas las generaciones que han formado parte de la Bycenes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte del evento inaugural, Julio C\u00e9sar Leyva Ruiz, titular de la Direcci\u00f3n General de Educaci\u00f3n Superior para el Magisterio (Dgesum), imparti\u00f3 la conferencia magistral \u201cTransformando la formaci\u00f3n docente: retos y perspectivas de los planes de estudio 2022\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora a 30 de marzo de 2025.- Con una s\u00f3lida trayectoria en la formaci\u00f3n docente y una visi\u00f3n de innovaci\u00f3n hacia el futuro, la Benem\u00e9rita y Centenaria Escuela Normal del Estado de Sonora \u201cProf. Jes\u00fas Manuel Bustamante Mungarro\u201d (Bycenes) inaugur\u00f3 la agenda de eventos para celebrar su 110 aniversario. En representaci\u00f3n de Froyl\u00e1n G\u00e1mez [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16879,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-16878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/16878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=16878"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/16878\/revisions"}],"predecessor-version":[{"id":16880,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/16878\/revisions\/16880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/16879"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=16878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=16878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=16878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}