{"id":16772,"date":"2025-03-26T15:05:15","date_gmt":"2025-03-26T22:05:15","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=16772"},"modified":"2025-03-26T15:05:19","modified_gmt":"2025-03-26T22:05:19","slug":"firma-unison-convenio-con-instituto-de-ciencias-pedagogicas-de-cuba","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/03\/26\/firma-unison-convenio-con-instituto-de-ciencias-pedagogicas-de-cuba\/","title":{"rendered":"Firma Unison convenio con instituto de ciencias pedag\u00f3gicas de Cuba."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 26 de marzo de 2025.- Con el fin de fortalecer v\u00ednculos con diferentes instituciones de educaci\u00f3n superior, a nivel internacional, se estableci\u00f3 un convenio de macro cooperaci\u00f3n entre la Universidad de Sonora y el Instituto Central de Ciencias Pedag\u00f3gicas (ICCP) de la Rep\u00fablica de Cuba, el cual atender\u00e1, principalmente a la Licenciatura en Educaci\u00f3n, pero tambi\u00e9n a la Licenciatura en Ling\u00fc\u00edstica y otras \u00e1reas afines a la pedagog\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En d\u00edas pasados, la rectora Mar\u00eda Rita Plancarte Mart\u00ednez y Silvia Mar\u00eda Navarro Quintero, directora General del ICCP, firmaron el documento que oficializ\u00f3 el inicio del intercambio acad\u00e9mico entre dichas instituciones, con la seguridad de que cada acci\u00f3n fortalecer\u00e1 la educaci\u00f3n entre Cuba y M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTenemos la seguridad de que, tanto el Instituto Central de Ciencias Pedag\u00f3gicas de la Rep\u00fablica de Cuba, como la Universidad de Sonora, tienen mucho que aportar, y este convenio fortalece el trabajo y la investigaci\u00f3n conjunta\u201d, afirm\u00f3 la rectora Plancarte Mart\u00ednez durante el evento llevado a cabo en La Habana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como testigo de honor, estuvo la ministra de educaci\u00f3n de Cuba, Naima Ariatne Trujillo Barreto, mientras que, por parte de la Unison, Susana Ang\u00e9lica Pastrana Corral, jefa del Departamento de Ciencias Sociales del Campus Caborca, fue part\u00edcipe del evento como impulsora de esta uni\u00f3n de esfuerzos entre ambas instituciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fortalecen \u00e1reas de educaci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este documento tiene por objetivo el desarrollo de actividades de superaci\u00f3n profesional, formaci\u00f3n acad\u00e9mica e investigaci\u00f3n para profesionales mexicanos que contribuyan a la elevaci\u00f3n continua de la calidad de la educaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, Pastrana Corral asegur\u00f3 que, con este convenio se fortalece, principalmente, el programa de Licenciatura en Educaci\u00f3n, en la capacitaci\u00f3n y formaci\u00f3n cient\u00edfica tanto de la planta docente como de estudiantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsto implica poder intercambiar los conocimientos en el \u00e1mbito de la educaci\u00f3n especial, que es tan importante que nuestros estudiantes salgan formados y fortalecidos en esa \u00e1rea que es constante, que tenemos y no sabemos c\u00f3mo afrontarla en momento dado, se requiere capacitar a nuestra planta docente\u201d, asever\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por parte del ICCP, aseguraron que es una prioridad el fortalecimiento de alianzas con otras instituciones, as\u00ed como el intercambio cient\u00edfico, la diversificaci\u00f3n de los servicios y la profesionalizaci\u00f3n de los especialistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora a 26 de marzo de 2025.- Con el fin de fortalecer v\u00ednculos con diferentes instituciones de educaci\u00f3n superior, a nivel internacional, se estableci\u00f3 un convenio de macro cooperaci\u00f3n entre la Universidad de Sonora y el Instituto Central de Ciencias Pedag\u00f3gicas (ICCP) de la Rep\u00fablica de Cuba, el cual atender\u00e1, principalmente a la Licenciatura [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-16772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/16772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=16772"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/16772\/revisions"}],"predecessor-version":[{"id":16774,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/16772\/revisions\/16774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/16773"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=16772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=16772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=16772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}