{"id":16769,"date":"2025-03-26T15:00:04","date_gmt":"2025-03-26T22:00:04","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=16769"},"modified":"2025-03-26T15:00:10","modified_gmt":"2025-03-26T22:00:10","slug":"lanzan-pagina-de-umpam-para-acercar-atencion-a-la-ciudadania","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/03\/26\/lanzan-pagina-de-umpam-para-acercar-atencion-a-la-ciudadania\/","title":{"rendered":"Lanzan p\u00e1gina de UMPAM para acercar atenci\u00f3n a la ciudadan\u00eda."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por medio de esta herramienta se podr\u00e1n agendar citas para que la Unidad Municipal para la Prevenci\u00f3n y Aplicaci\u00f3n de Medidas para Adolescentes atienda reportes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hermosillo, Sonora a 26 de marzo de 2025.-\u00a0<\/strong>Para dar a conocer cu\u00e1les son las funciones y atender de manera m\u00e1s r\u00e1pida a la ciudadan\u00eda, se cre\u00f3 la p\u00e1gina de la Unidad Municipal para la Prevenci\u00f3n y Aplicaci\u00f3n de Medidas para Adolescentes, \u00f3rgano encargado de atender la comisi\u00f3n de faltas administrativas por adolescentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl objetivo de crear esta p\u00e1gina es tener ese acercamiento con la ciudadan\u00eda porque muchas veces dentro de la colonia detectamos a j\u00f3venes que est\u00e1n haciendo da\u00f1o, que bajan t\u00e9rmicos, que escandalizan, que asustan a los ni\u00f1os y pensamos en no faltar al trabajo, dar vueltas o simplemente no saber a d\u00f3nde acudir\u201d, coment\u00f3 la directora del \u00e1rea, Martha Flores Contreras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precis\u00f3 que el fin es que la persona afectada genere su cita a trav\u00e9s de un c\u00f3digo QR, explique la situaci\u00f3n, proporcione sus datos y el personal se comunicar\u00e1 para dar seguimiento y si no es UMPAM el lugar indicado, se le orienta para que se sienta escuchada y apoyada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Flores Contreras explic\u00f3 que la principal funci\u00f3n es atender a los j\u00f3venes presentados por la Polic\u00eda Municipal que cometen infracciones administrativas, como ri\u00f1a, escandalizar en la v\u00eda p\u00fablica y andar bajo los efectos de alguna droga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La p\u00e1gina web umpam.hermosillo.gob.mx tambi\u00e9n contiene informaci\u00f3n sobre el \u00e1rea, su historia, acciones, embajadores como casos de \u00e9xito, as\u00ed como sus colaboradores, que son organismos p\u00fablicos y privados a donde se canaliza al adolescente infractor a cumplir su medida impuesta, la cual es personalizada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por medio de esta herramienta se podr\u00e1n agendar citas para que la Unidad Municipal para la Prevenci\u00f3n y Aplicaci\u00f3n de Medidas para Adolescentes atienda reportes. Hermosillo, Sonora a 26 de marzo de 2025.-\u00a0Para dar a conocer cu\u00e1les son las funciones y atender de manera m\u00e1s r\u00e1pida a la ciudadan\u00eda, se cre\u00f3 la p\u00e1gina de la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16770,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-16769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/16769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=16769"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/16769\/revisions"}],"predecessor-version":[{"id":16771,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/16769\/revisions\/16771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/16770"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=16769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=16769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=16769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}