{"id":15551,"date":"2025-02-18T23:06:02","date_gmt":"2025-02-19T06:06:02","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=15551"},"modified":"2025-02-18T23:06:07","modified_gmt":"2025-02-19T06:06:07","slug":"parques-y-jardines-busca-escuelas-que-quieran-ser-reforestadas-en-hermosillo","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/02\/18\/parques-y-jardines-busca-escuelas-que-quieran-ser-reforestadas-en-hermosillo\/","title":{"rendered":"Parques y Jardines busca escuelas que quieran ser reforestadas en Hermosillo."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 18 de febrero de 2025.- Parques y Jardines de Hermosillo planea reforestar escuelas de todos los niveles educativos, ya que son terrenos grandes que se pueden aprovechar para plantar vegetaci\u00f3n nativa de la regi\u00f3n, dijo su titular, Amparo Fontanot.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que la capital sonorense necesita de m\u00e1s vegetaci\u00f3n nativa, pero los parques y plazas son peque\u00f1os, en comparaci\u00f3n con los terrenos de las escuelas que son m\u00e1s grandes. Con ello, se contribuir\u00e1 a seguir reforestando la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Nosotros trabajamos de acuerdo a peticiones de las escuelas. Llegan a nosotros y nos dicen: oye, me interesa reforestar mi escuela. Entonces vamos, los visitamos, hacemos un diagn\u00f3stico de las necesidades y entonces ah\u00ed determinamos cu\u00e1ntos \u00e1rboles pueden cuidar, qu\u00e9 \u00e1rboles son correctos en ese espacio&#8221;, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amparo Fontanot se\u00f1al\u00f3 que las escuelas deben presentar un oficio a las oficinas de Parques y Jardines, ubicadas en la calle Carb\u00f3, esquina con Morelia, colonia Casa Blanca, de 08:00 a 15:00 horas, de lunes a viernes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Estamos haciendo un diagn\u00f3stico, ver qui\u00e9n se anima para trabajar con nosotros y tener un n\u00famero real de cu\u00e1ntas escuelas solicitar\u00e1n la reforestaci\u00f3n&#8221;, indic\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora a 18 de febrero de 2025.- Parques y Jardines de Hermosillo planea reforestar escuelas de todos los niveles educativos, ya que son terrenos grandes que se pueden aprovechar para plantar vegetaci\u00f3n nativa de la regi\u00f3n, dijo su titular, Amparo Fontanot. Explic\u00f3 que la capital sonorense necesita de m\u00e1s vegetaci\u00f3n nativa, pero los parques [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15552,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-15551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/15551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=15551"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/15551\/revisions"}],"predecessor-version":[{"id":15553,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/15551\/revisions\/15553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/15552"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=15551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=15551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=15551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}