{"id":15374,"date":"2025-02-13T17:53:28","date_gmt":"2025-02-14T00:53:28","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=15374"},"modified":"2025-02-13T17:53:30","modified_gmt":"2025-02-14T00:53:30","slug":"gobernador-durazo-consolida-alianza-con-nadbank-para-impulsar-infraestructura-sostenible-en-la-frontera-norte","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/02\/13\/gobernador-durazo-consolida-alianza-con-nadbank-para-impulsar-infraestructura-sostenible-en-la-frontera-norte\/","title":{"rendered":"Gobernador Durazo consolida alianza con NADBank para impulsar infraestructura sostenible en la frontera norte."},"content":{"rendered":"\n<p>Hermosillo, Sonora a 13 de febrero de 2025.- El Plan Sonora de Energ\u00edas Sostenibles sigue consolid\u00e1ndose como un modelo de referencia internacional, al generar alianzas estrat\u00e9gicas con organismos de alto impacto. Como parte de esta visi\u00f3n, el gobernador Alfonso Durazo Monta\u00f1o firm\u00f3 un memorando de entendimiento con John Beckham, director general del Banco de Desarrollo de Am\u00e9rica del Norte (NADBank), para impulsar infraestructura sustentable en la frontera norte del estado.<\/p>\n\n\n\n<p>Este acuerdo busca fomentar inversiones en proyectos alineados con la transici\u00f3n energ\u00e9tica y el desarrollo sostenible, en coordinaci\u00f3n con instituciones acad\u00e9micas y organismos especializados.<\/p>\n\n\n\n<p>\u201cFirmamos un memorando de entendimiento para trabajar en iniciativas medioambientales clave para el estado de Sonora. Agradezco el respaldo del NADBank, que hist\u00f3ricamente ha sido un actor fundamental en el mejoramiento ambiental de la frontera\u201d, destac\u00f3 el gobernador Durazo.<\/p>\n\n\n\n<p>Por su parte, John Beckham, director general del NADBank, subray\u00f3 que esta sinergia permitir\u00e1 atraer inversiones en infraestructura con altos est\u00e1ndares de calidad y sostenibilidad.<\/p>\n\n\n\n<p>\u201cEl objetivo del banco es apoyar a las comunidades fronterizas de M\u00e9xico y Estados Unidos en la inversi\u00f3n de infraestructura necesaria para garantizar bienestar y prosperidad. Este es solo el inicio de una gran colaboraci\u00f3n\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>En calidad de testigo de honor, Alicia B\u00e1rcena Ibarra, secretaria de Medio Ambiente y Recursos Naturales, resalt\u00f3 el papel clave de las instituciones binacionales en el desarrollo de la regi\u00f3n fronteriza.<\/p>\n\n\n\n<p>\u201cM\u00e9xico cuenta con organismos s\u00f3lidos de car\u00e1cter binacional, y uno de ellos es el NADBank. Es un honor ser testigo de este convenio, que contribuir\u00e1 significativamente al desarrollo sostenible de nuestra frontera\u201d, concluy\u00f3.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" class=\"wp-image-15375\" style=\"width: 500px;\" src=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/02\/36e1d5c3-43fd-4ec9-a2ff-bf1b5d8694ce.jpg\" alt=\"\" srcset=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/02\/36e1d5c3-43fd-4ec9-a2ff-bf1b5d8694ce.jpg 1280w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/02\/36e1d5c3-43fd-4ec9-a2ff-bf1b5d8694ce-300x200.jpg 300w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/02\/36e1d5c3-43fd-4ec9-a2ff-bf1b5d8694ce-1024x682.jpg 1024w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/02\/36e1d5c3-43fd-4ec9-a2ff-bf1b5d8694ce-768x512.jpg 768w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/02\/36e1d5c3-43fd-4ec9-a2ff-bf1b5d8694ce-750x500.jpg 750w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/02\/36e1d5c3-43fd-4ec9-a2ff-bf1b5d8694ce-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora a 13 de febrero de 2025.- El Plan Sonora de Energ\u00edas Sostenibles sigue consolid\u00e1ndose como un modelo de referencia internacional, al generar alianzas estrat\u00e9gicas con organismos de alto impacto. Como parte de esta visi\u00f3n, el gobernador Alfonso Durazo Monta\u00f1o firm\u00f3 un memorando de entendimiento con John Beckham, director general del Banco de Desarrollo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15376,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-15374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/15374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=15374"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/15374\/revisions"}],"predecessor-version":[{"id":15377,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/15374\/revisions\/15377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/15376"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=15374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=15374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=15374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}