{"id":15309,"date":"2025-02-12T20:23:32","date_gmt":"2025-02-13T03:23:32","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=15309"},"modified":"2025-02-12T20:23:33","modified_gmt":"2025-02-13T03:23:33","slug":"exhorta-sec-a-completar-el-registro-de-inscripciones-anticipadas-froylan-gamez","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/02\/12\/exhorta-sec-a-completar-el-registro-de-inscripciones-anticipadas-froylan-gamez\/","title":{"rendered":"Exhorta SEC a completar el registro de Inscripciones Anticipadas: Froyl\u00e1n G\u00e1mez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 12 de febrero de 2025.- El proceso de Inscripciones Anticipadas permitir\u00e1 programar la asignaci\u00f3n de docentes, recursos materiales e infraestructura educativa para el ciclo escolar 2025-2026, destac\u00f3 Froyl\u00e1n G\u00e1mez Gamboa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El titular de la Secretar\u00eda de Educaci\u00f3n y Cultura (SEC) exhort\u00f3 a padres y madres de familia, as\u00ed como tutores, a completar el registro del alumnado a trav\u00e9s del portal www.yoremia.gob.mx, el cual permanecer\u00e1 activo hasta las 23:59 horas del s\u00e1bado 15 de febrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resalt\u00f3 que se trata de un proceso \u00e1gil y sencillo en el que solo tienen que capturar la CURP, verificar los datos de nacimiento o generar un registro nuevo, seleccionar tres escuelas de inter\u00e9s, registrar los datos solicitados, actualizar tallas del uniforme escolar gratuito y descargar e imprimir la Ficha de Inscripci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">G\u00e1mez Gamboa subray\u00f3 que la SEC brinda orientaci\u00f3n a trav\u00e9s de la L\u00ednea de la Educaci\u00f3n: 6622 89 76 01 al 05, en un horario de 8:00 a 16:00 horas de lunes a viernes; chat en l\u00ednea en la p\u00e1gina https:\/\/educacion.sonora.gob.mx\/ y por WhatsApp: 6624 505513 y 6623 557522.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puntualiz\u00f3 que las Inscripciones Anticipadas se llevan a cabo cada a\u00f1o para registrar al alumnado que ingresar\u00e1 a preescolar, primero de primaria y primero de secundaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora a 12 de febrero de 2025.- El proceso de Inscripciones Anticipadas permitir\u00e1 programar la asignaci\u00f3n de docentes, recursos materiales e infraestructura educativa para el ciclo escolar 2025-2026, destac\u00f3 Froyl\u00e1n G\u00e1mez Gamboa. El titular de la Secretar\u00eda de Educaci\u00f3n y Cultura (SEC) exhort\u00f3 a padres y madres de familia, as\u00ed como tutores, a completar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-15309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/15309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=15309"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/15309\/revisions"}],"predecessor-version":[{"id":15311,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/15309\/revisions\/15311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/15310"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=15309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=15309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=15309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}