{"id":14442,"date":"2025-01-21T20:26:25","date_gmt":"2025-01-22T03:26:25","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=14442"},"modified":"2025-01-21T20:26:26","modified_gmt":"2025-01-22T03:26:26","slug":"modifica-sec-horario-de-clases-en-41-municipios-ante-pronostico-de-bajas-temperaturas","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/01\/21\/modifica-sec-horario-de-clases-en-41-municipios-ante-pronostico-de-bajas-temperaturas\/","title":{"rendered":"Modifica SEC horario de clases en 41 municipios ante pron\u00f3stico de bajas temperaturas."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hizo un llamado a enviar bien abrigados a los estudiantes para cuidar su salud ante la llegada del Frente Fr\u00edo 24.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 21 de enero de 2025.- Del 22 al 24 de enero se modificar\u00e1 el horario de clases en 41 municipios de la entidad, ante los pron\u00f3sticos de bajas temperaturas, anunci\u00f3 el titular de la Secretar\u00eda de Educaci\u00f3n y Cultura (SEC), Froyl\u00e1n G\u00e1mez Gamboa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario estatal detall\u00f3 que con base a las recomendaciones de la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC), la entrada a clases ser\u00e1 una hora despu\u00e9s, en el turno matutino y se adelantar\u00e1 una hora la salida en el turno vespertino, en escuelas p\u00fablicas y particulares de nivel b\u00e1sico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Especific\u00f3 que los municipios donde se aplicar\u00e1 dicha medida preventiva para proteger la salud de la comunidad escolar son: Hu\u00e1sabas, Bacerac, Fronteras, Agua Prieta, Nacozari de Garc\u00eda, Huachinera, Bavispe, Villa Hidalgo, Cumpas, San Pedro de la Cueva, Soyopa, Divisaderos, Moctezuma y Granados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, en Bacanora, Sahuaripa, Bacad\u00e9huachi, Tepache, N\u00e1cori Chico, Arivechi, \u00d3navas, Y\u00e9cora, \u00cdmuris, Cucurpe, Nogales, Arizpe, Naco, Cananea, Bacoachi, Santa Cruz, San Javier, Ban\u00e1michi, Hu\u00e9pac, San Felipe de Jes\u00fas, Aconchi, Bavi\u00e1cora, Magdalena, Tubutama, S\u00e1ric, Quiriego y Rosario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">G\u00e1mez Gamboa abund\u00f3 que, seg\u00fan datos proporcionados por la CEPC, a ra\u00edz del ingreso de una masa de aire \u00e1rtico, asociada al Frente Fr\u00edo 24, generar\u00e1n descenso marcado de temperaturas que en combinaci\u00f3n con rachas de vientos afectar\u00e1n la sensaci\u00f3n t\u00e9rmica que variar\u00e1 de -6 a -12 grados cent\u00edgrados en estos municipios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario estatal exhort\u00f3 a la sociedad en general a permanecer atenta a cualquier aviso que emitan las autoridades correspondientes a trav\u00e9s de los medios oficiales de informaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hizo un llamado a enviar bien abrigados a los estudiantes para cuidar su salud ante la llegada del Frente Fr\u00edo 24. Hermosillo, Sonora a 21 de enero de 2025.- Del 22 al 24 de enero se modificar\u00e1 el horario de clases en 41 municipios de la entidad, ante los pron\u00f3sticos de bajas temperaturas, anunci\u00f3 el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-14442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/14442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=14442"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/14442\/revisions"}],"predecessor-version":[{"id":14444,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/14442\/revisions\/14444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/14443"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=14442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=14442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=14442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}