{"id":14312,"date":"2025-01-19T20:53:31","date_gmt":"2025-01-20T03:53:31","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=14312"},"modified":"2025-01-19T21:04:41","modified_gmt":"2025-01-20T04:04:41","slug":"apoya-gobierno-de-sonora-a-docentes-de-educacion-fisica-con-uniformes-y-material-deportivo","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2025\/01\/19\/apoya-gobierno-de-sonora-a-docentes-de-educacion-fisica-con-uniformes-y-material-deportivo\/","title":{"rendered":"Entregan a docentes de Educaci\u00f3n F\u00edsica uniformes y material deportivo."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora a 19 de enero de 2025.- Con una inversi\u00f3n de alrededor de ocho millones de pesos, el Gobierno de Sonora entreg\u00f3 uniformes y material did\u00e1ctico deportivo a mil 115 docentes de Educaci\u00f3n F\u00edsica de la entidad, destac\u00f3 Froyl\u00e1n G\u00e1mez Gamboa, secretario de Educaci\u00f3n y Cultura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El titular de la SEC resalt\u00f3 que Sonora es el \u00fanico estado que otorga este tipo de apoyos, como parte del compromiso para que el colectivo cuente con las herramientas necesarias para participar plenamente en el desarrollo de la clase, como parte del compromiso del gobernador Alfonso Durazo en la igualdad de oportunidades y en el poder transformador de la educaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">G\u00e1mez Gamboa detall\u00f3 que la inversi\u00f3n para la adquisici\u00f3n de los uniformes a docentes es de alrededor de tres millones de pesos, mientras que para el material did\u00e1ctico que usar\u00e1n en las clases de Educaci\u00f3n F\u00edsica se destinaron casi cinco millones de pesos en beneficio de 333 mil 600 estudiantes de nivel b\u00e1sico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario estatal reconoci\u00f3 el esfuerzo y dedicaci\u00f3n de las y los docentes de dicha asignatura ya que su labor es invaluable para garantizar el bienestar y el desarrollo integral de las ni\u00f1as, ni\u00f1os y j\u00f3venes sonorenses que cursan sus estudios en escuelas de Educaci\u00f3n Especial, preescolar, primaria, secundaria y telesecundaria. Cada docente recibir\u00e1 un paquete que incluye pants, chamarra, camisa tipo polo, playera tipo jersey y pantal\u00f3n corto o short.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" class=\"wp-image-14313\" style=\"width: 400px;\" src=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/b76145e1-44b0-45a5-b528-c0ebf8a1e157.jpg\" alt=\"\" srcset=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/b76145e1-44b0-45a5-b528-c0ebf8a1e157.jpg 1600w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/b76145e1-44b0-45a5-b528-c0ebf8a1e157-300x200.jpg 300w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/b76145e1-44b0-45a5-b528-c0ebf8a1e157-1024x682.jpg 1024w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/b76145e1-44b0-45a5-b528-c0ebf8a1e157-768x512.jpg 768w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/b76145e1-44b0-45a5-b528-c0ebf8a1e157-1536x1023.jpg 1536w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/b76145e1-44b0-45a5-b528-c0ebf8a1e157-750x500.jpg 750w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/b76145e1-44b0-45a5-b528-c0ebf8a1e157-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                                 <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" class=\"wp-image-14314\" style=\"width: 400px;\" src=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/bcfaa558-fc30-4b5d-8a2d-4b37e1bdfdca.jpg\" alt=\"\" srcset=\"https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/bcfaa558-fc30-4b5d-8a2d-4b37e1bdfdca.jpg 1600w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/bcfaa558-fc30-4b5d-8a2d-4b37e1bdfdca-300x200.jpg 300w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/bcfaa558-fc30-4b5d-8a2d-4b37e1bdfdca-1024x682.jpg 1024w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/bcfaa558-fc30-4b5d-8a2d-4b37e1bdfdca-768x512.jpg 768w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/bcfaa558-fc30-4b5d-8a2d-4b37e1bdfdca-1536x1023.jpg 1536w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/bcfaa558-fc30-4b5d-8a2d-4b37e1bdfdca-750x500.jpg 750w, https:\/\/elreporterodelacomunidad.com\/wp-content\/uploads\/2025\/01\/bcfaa558-fc30-4b5d-8a2d-4b37e1bdfdca-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora a 19 de enero de 2025.- Con una inversi\u00f3n de alrededor de ocho millones de pesos, el Gobierno de Sonora entreg\u00f3 uniformes y material did\u00e1ctico deportivo a mil 115 docentes de Educaci\u00f3n F\u00edsica de la entidad, destac\u00f3 Froyl\u00e1n G\u00e1mez Gamboa, secretario de Educaci\u00f3n y Cultura. El titular de la SEC resalt\u00f3 que Sonora [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-14312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/14312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=14312"}],"version-history":[{"count":2,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/14312\/revisions"}],"predecessor-version":[{"id":14316,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/14312\/revisions\/14316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/14317"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=14312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=14312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=14312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}