{"id":10044,"date":"2024-10-07T19:29:00","date_gmt":"2024-10-08T02:29:00","guid":{"rendered":"https:\/\/elreporterodelacomunidad.com\/?p=10044"},"modified":"2024-10-07T19:29:02","modified_gmt":"2024-10-08T02:29:02","slug":"taylor-swift-ya-es-la-artista-mas-rica-del-mundo","status":"publish","type":"post","link":"https:\/\/elreporterodelacomunidad.com\/index.php\/2024\/10\/07\/taylor-swift-ya-es-la-artista-mas-rica-del-mundo\/","title":{"rendered":"Taylor Swift ya es la artista m\u00e1s rica del mundo."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Swift tuvo este crecimiento en su fortuna tras el \u00e9xito arrollador de su \u2018Eras Tour\u2019 y al creciente valor de su cat\u00e1logo musical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados unidos a 07 de octubre del 2024.- Taylor Swift se convirti\u00f3 en la cantante m\u00e1s rica del mundo, seg\u00fan la \u00faltima actualizaci\u00f3n de Forbes, que sit\u00faa su patrimonio neto en unos asombrosos 1,600 millones de d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este incremento en su fortuna se debe al \u00e9xito arrollador de su \u201cEras Tour\u201d y al creciente valor de su cat\u00e1logo musical, lo que ya la hab\u00eda convertido en multimillonaria desde octubre de 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Casi 600 millones provienen de regal\u00edas y giras, mientras que otros 600 millones provienen de su cat\u00e1logo musical. Adem\u00e1s, posee aproximadamente 125 millones de d\u00f3lares en bienes ra\u00edces.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta actualizaci\u00f3n, Swift supera a Rihanna, quien ten\u00eda un patrimonio neto de 1,400 millones de d\u00f3lares, y se posiciona como la segunda m\u00fasico m\u00e1s rica, solo por detr\u00e1s de JAY-Z, quien posee 2,500 millones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe recordar que, a principios de abril, Swift se ubicaba en el puesto 14 entre las celebridades multimillonarias con 1,100 millones de d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su \u201cEras Tour\u201d, que se convirti\u00f3 en la primera gira en la historia en alcanzar los mil millones de d\u00f3lares en diciembre de 2023, gener\u00f3 un asombroso ingreso de mil millones despu\u00e9s de 60 conciertos en solo ocho meses y se espera que genere otro mil millones para 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Swift tuvo este crecimiento en su fortuna tras el \u00e9xito arrollador de su \u2018Eras Tour\u2019 y al creciente valor de su cat\u00e1logo musical. Estados unidos a 07 de octubre del 2024.- Taylor Swift se convirti\u00f3 en la cantante m\u00e1s rica del mundo, seg\u00fan la \u00faltima actualizaci\u00f3n de Forbes, que sit\u00faa su patrimonio neto en unos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-10044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/10044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=10044"}],"version-history":[{"count":1,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/10044\/revisions"}],"predecessor-version":[{"id":10046,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/posts\/10044\/revisions\/10046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media\/10045"}],"wp:attachment":[{"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=10044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=10044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterodelacomunidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=10044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}